{"id":32011,"date":"2025-01-14T22:00:37","date_gmt":"2025-01-14T22:00:37","guid":{"rendered":"https:\/\/www.solinst.com\/ueber\/"},"modified":"2026-05-05T21:39:11","modified_gmt":"2026-05-05T21:39:11","slug":"ueber","status":"publish","type":"page","link":"https:\/\/www.solinst.com\/de\/ueber\/","title":{"rendered":"\u00dcber"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_image src=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-canada-building-1920&#215;500-1.webp&#8220; alt=&#8220;Erfahren Sie mehr \u00fcber Solinst Kanada&#8220; title_text=&#8220;Erfahren Sie mehr \u00fcber Solinst Kanada&#8220; src_tablet=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-canada-building-965&#215;500-1.webp&#8220; src_phone=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-canada-building-965&#215;500-1.webp&#8220; src_last_edited=&#8220;on|phone&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;H1 and breadcrumbs&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;792ca5bd-0808-46bd-9ce7-3bcb8e74f4d3&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;4b28f470-0d73-4e9d-b92d-e6f41f2cea24&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_heading title=&#8220;Solinst Canada Ltd.&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;6983e4e7-a6e0-4a8d-b486-49939fd240c0&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][dsm_breadcrumbs _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; home_icon_text_color=&#8220;#d6d6d6&#8243; global_colors_info=&#8220;{}&#8220;][\/dsm_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Mobile-Only Nav with Offset&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;4759a92f-4b27-4854-bb2c-299854634e93&#8243; global_module=&#8220;32811&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;90%&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code admin_label=&#8220;\u00dcber Mobile Nav &#8211; Dropdown ausw\u00e4hlen&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_css_free_form=&#8220;select {||||      font-size: 1em; \/* Adjust font size *\/||      padding: 10px;   \/* Optional: Increase padding for better spacing *\/||      width: 100%;||      box-sizing: border-box;\/* Optional: Adjust width to fit the container *\/||      height: 50px;||}||||    \/* Style for dropdown options (fallback if needed) *\/||select option {||      font-size: 1.2em; \/* Ensures option text matches select styling *\/||      width: 100%;||    }&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<select name=\"dropdown\" onchange=\"location = this.value;\"><!-- [et_pb_line_break_holder] --><option value=\"\">\u00dcber das Men\u00fc<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about-us\/\">\u00dcber Solinst<\/option><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about-us\/quality-service\/\">-Qualit\u00e4t und Service<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about-us\/commitment-research\/\">-Verpflichtung zur Forschung<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about-us\/new-era\/\">-Pegelmessung tritt in eine neue \u00c4ra ein!<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about-us\/solinst-warranty\/\">-Solinst-Garantie<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about\/warranty.pdf\">&#8211;Download Solinst-Garantie (PDF)<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/maps.app.goo.gl\/5cRZkKav1byanosv7\">-Online-Karte zu Solinst<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/about\/solinst-map.pdf\">-Landkarte zu Solinst herunterladen (PDF)<\/option><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/select>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; specialty=&#8220;on&#8220; padding_top_1=&#8220;0px&#8220; padding_top_2=&#8220;0px&#8220; padding_top_bottom_link_1=&#8220;false&#8220; padding_top_bottom_link_2=&#8220;false&#8220; padding_left_right_link_1=&#8220;false&#8220; padding_left_right_link_2=&#8220;false&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; inner_width=&#8220;90%&#8220; inner_max_width=&#8220;1600px&#8220; custom_margin=&#8220;0px||||false|false&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_menu menu_id=&#8220;234&#8243; admin_label=&#8220;About Main Nav&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;242faa89-ac4f-4e46-90fe-505e8c1eab79&#8243; global_module=&#8220;33239&#8243; global_colors_info=&#8220;{}&#8220;][\/et_pb_menu][et_pb_slider disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; display_conditions=&#8220;W10=&#8220; link_option_url=&#8220;https:\/\/www.solinst.com\/instruments\/dataloggers-and-telemetry-systems\/3001-levelogger\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position1&#038;utm_campaign=3001&#8243; global_module=&#8220;53188&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_slide button_text=&#8220;Levelogger&#8220; button_link=&#8220;https:\/\/www.solinst.com\/de\/produkte\/datenlogger-und-telemetriesysteme\/3001-levelogger\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position1&amp;utm_campaign=3001&#8243; use_bg_overlay=&#8220;on&#8220; bg_overlay_color=&#8220;rgba(224,97,0,0.58)&#8220; button_text_tablet=&#8220;&#8220; button_text_phone=&#8220;&#8220; button_text_last_edited=&#8220;on|desktop&#8220; content_tablet=&#8220;&#8220; content_phone=&#8220;&#8220; content_last_edited=&#8220;on|desktop&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;#F07C00&#8243; background_enable_color=&#8220;on&#8220; background_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-absolute-water-level-datalogging.webp&#8220; background_enable_image=&#8220;on&#8220; background_position=&#8220;top_center&#8220; custom_button=&#8220;on&#8220; button_bg_color=&#8220;#f58025&#8243; button_border_width=&#8220;2px&#8220; button_border_color=&#8220;#ffffff&#8220; button_border_radius=&#8220;20px&#8220; button_font=&#8220;|600|||||||&#8220; hover_enabled=&#8220;0&#8243; background_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220; button_border_width__hover_enabled=&#8220;on|hover&#8220; button_border_width__hover=&#8220;2px&#8220; sticky_transition=&#8220;on&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h2>Genaue Wasserstandsdaten<\/h2>\n<p><b>Zuverl\u00e4ssige und langlebige Instrumente<\/b><\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][et_pb_slider disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; link_option_url=&#8220;https:\/\/www.solinst.com\/careers\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position2&#038;utm_campaign=SUK-regional-sales-manager&#8220; hover_enabled=&#8220;0&#8243; global_module=&#8220;53561&#8243; saved_tabs=&#8220;all&#8220; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][et_pb_slide heading=&#8220;Solinst UK stellt ein!&#8220; button_text=&#8220;Regionaler Verkaufsleiter&#8220; button_link=&#8220;https:\/\/www.solinst.com\/careers\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position2&amp;utm_campaign=SUK-regional-sales-manager&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;38px&#8220; background_color=&#8220;RGBA(255,255,255,0)&#8220; background_enable_color=&#8220;on&#8220; background_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-ltd.webp&#8220; background_enable_image=&#8220;on&#8220; background_size=&#8220;contain&#8220; custom_button=&#8220;on&#8220; button_bg_color=&#8220;#f58025&#8243; button_border_width=&#8220;2px&#8220; button_border_radius=&#8220;20px&#8220; button_font=&#8220;|600|||||||&#8220; button_custom_margin=&#8220;||||false|false&#8220; button_custom_padding=&#8220;1px||||false|false&#8220; custom_padding=&#8220;76px||||false|false&#8220; hover_enabled=&#8220;0&#8243; header_text_shadow_style=&#8220;preset5&#8243; global_colors_info=&#8220;{}&#8220; sticky_transition=&#8220;on&#8220; sticky_enabled=&#8220;0&#8243; button_border_color=&#8220;#ffffff&#8220;]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][et_pb_column type=&#8220;3_4&#8243; specialty_columns=&#8220;3&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3676f7e6-7b83-4698-94ce-2cc9fa9ae43d&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Solinst Kanada Ltd.  <\/strong>Das 1975 gegr\u00fcndete Unternehmen Solinst hat seit langem die Vision, zuverl\u00e4ssige, qualitativ hochwertige L\u00f6sungen f\u00fcr Grundwasserfachleute auf der ganzen Welt anzubieten. Im Laufe der Jahre hat sich das Unternehmen zu einem angesehenen Branchenf\u00fchrer entwickelt, der f\u00fcr seine innovativen Produkte und sein Engagement f\u00fcr die Weiterentwicklung der Wasser\u00fcberwachungstechnologie bekannt ist. <\/p>\n<p>Solinst begann in einem kleinen Industriegeb\u00e4ude in Burlington, Ontario, und befindet sich heute in einer gro\u00dfen Anlage in Georgetown, Ontario, und ist weiterhin ein erfolgreiches Unternehmen im Besitz der Familie Belshaw. Solinst ist stolz darauf, dass alles im eigenen Haus gemacht wird, vom Design, der Entwicklung und der Produktion bis hin zum technischen Verkaufssupport und Kundendienst. <\/p>\n<p>Im Laufe seiner Geschichte hat Solinst seine Produktlinie kontinuierlich erweitert und bietet eine Reihe von Instrumenten an, die auf Pr\u00e4zision und Langlebigkeit ausgelegt sind. Vom kultigen Wasserstandsmessger\u00e4t Modell 101 bis hin zur fortschrittlichen Levelogger-Serie sind die Instrumente von Solinst zu unverzichtbaren Werkzeugen f\u00fcr Hydrogeologen, Umweltberater und Wasserressourcenmanager auf der ganzen Welt geworden. <\/p>\n<p>Das Engagement des Unternehmens f\u00fcr Innovationen wird auch durch die j\u00fcngste \u00dcbernahme von Flexible Liner Underground Technologies (jetzt <strong><a href=\"https:\/\/www.solinst.com\/de\/produkte\/solinst-floete\/\" title=\"Solinst Flute Flexible Liner Underground Technologies\">Solinst Flute<\/a><\/strong>), die das Unternehmen in die Lage versetzt, umfassende L\u00f6sungen f\u00fcr komplexe hydrogeologische Herausforderungen anzubieten. K\u00fcrzlich hat Solinst Canada die gesamten Verm\u00f6genswerte von Eureka Water Probes erworben, und die gesamte Palette der Eureka-Ger\u00e4te zur \u00dcberwachung der Wasserqualit\u00e4t ist erh\u00e4ltlich \u00fcber <a href=\"https:\/\/www.solinst.com\/de\/produkte\/solinst-eureka\/\" title=\"Solinst Eureka-Wassersonden\"><strong>Solinst Eureka LLC<\/strong><\/a><\/p>\n<p>Der Erfolg von Solinst beruht auf seinem Engagement f\u00fcr hohe Qualit\u00e4t, Kundenbetreuung und kontinuierliche Verbesserung. Das Unternehmen ist stolz auf seine starken Beziehungen zu Kunden, Partnern und einem weltweiten Vertriebsnetz, die auf Vertrauen und Zuverl\u00e4ssigkeit basieren. <\/p>\n<p>Solinst gedenkt dieses goldenen Jubil\u00e4ums, blickt auf sein reiches Erbe zur\u00fcck und freut sich auf eine Zukunft voller neuer M\u00f6glichkeiten und Fortschritte. Mit der konsequenten Ausrichtung auf innovative L\u00f6sungen und au\u00dfergew\u00f6hnlichen Service ist Solinst Canada Ltd. gut positioniert, um noch viele Jahre lang f\u00fchrend in der Wasser\u00fcberwachung zu sein. <\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3676f7e6-7b83-4698-94ce-2cc9fa9ae43d&#8220; width=&#8220;90%&#8220; max_width=&#8220;1600px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;4.27.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_2_font_size=&#8220;30px&#8220; header_2_line_height=&#8220;1.3em&#8220; custom_margin=&#8220;||1px|||&#8220; link_option_url=&#8220;https:\/\/www.solinst.com\/onthelevel-news\/water-level-monitoring\/water-level-datalogging\/assessing-coastal-flood-vulnerability-to-sea-level-rise\/&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2 role=\"heading\" aria-level=\"2\" data-uw-rm-heading=\"level\" style=\"text-align: center;\"><strong>Solinst feiert 50 Jahre<br \/><\/strong><\/h2>\n<p>[\/et_pb_text][dmg_masonry_gallery gallery=&#8220;40929,38734,43129,38745,40896,38756,40885,38767,38778,38800,38811,38822,38833,38789,38844,38855,38866,38877,38888,38899,38910,38921,38932,38943,38954,38965,38976,38987,38998,39009,39020,39031,39042,39053,39064,39075,39086,39097,39108,39119,39130,39141,39152,43754,43743,43732,43721,43710,43699,43688,43677,43666,43655,43644,43633,43622,43611,43600,43589,43578,43567,43556,43545,43534,43523,43512,43499,43479,43461,43450,43439,43428,43417,43406,43395,43384,43372,43361,43350,43339,43328,43316,43305,43294,43283,43272,43261,43250,43239,43228,43217,43206,43195,43184,43173,43162,43151,43140,43118,43107,43096,43085,43074,43063,43052,43041,43030,43019,43008,42997,42986,42975,42964,42953,42942,42931,42920,42909,42898,42887,42876,42865,42854,42843,42832,42821,42810,42799,42788,42777,42766,42755,42744,42733,42722,42711,42700,42689,42678,42667,42656,42645,42634,42623,42612,42601,42590,42579,42568,42557,42546,42535,42524,42513,42502,42491,42480,42469,42458,42447,42436,42425,42414,42403,42392,42381,42370,42359,42348,42337,42326,42315,42304,42293,42282,42271,42260,42249,42238,42226,42215,42204,42193,42182,42171,42160,42149,42138,42127,42116,42105,42094,42083,42072,42061,42050,42039,42028,42017,42006,41995,41984,41973,41962,41951,41940,41929,41918,41907,41896,41885,41874,41863,41852,41841,41830,41819,41808,41797,41786,41775,41764,41753,41742,41731,41720,41709,41698,41687,41676,41665,41654,41643,41632,41621,41610,41599,41382,41371,41359,41348,41337,41326,41315,41304,41293,41282,41271,41260,41249,41238,41227,41216,41205,41194,41183,41172,41161,41150,41139,41128,41117,41106,41095,41084,41073,41062,41051,41040,41029,41018,41007,40996,40985,40974,40963,40951,40940,40918,40907,40874,40863,40852,40841,40830,40819,40805,40791,40778,40765,40749,40734,40717,40700,40684,40670,40656,40640,40626,40612,40597,40584,40569,40556,40541,40528,40515,40499,40485,40472,40459,40448,40437,40426,40415,40404,40393,40327,40382,40371,40360,40349,40338,40316,40305,40294,40283,40257,40246,40235,40224,40213,40202,40191,40180,40169,40158,40147,40136,40125,40114,40103,40092,40081,40070,40059,40048,40037,40026,40015,40004,39993,39982,39971,39960,39949,39938,39927,39916,39905,39894,39883,39872,39850,39839,39828,39817,39806,39795,39784,39773,39762,39751,39740,39729,39718,39707,39696,39685,39674,39663,39652,39641,39630,39619,39608,39597,39586,39575,39564,39553,39542,39531,39520,39509,39498,39487,39476,39465,39454,39443,39432,39421,39410,39399,39388,39377,39366&#8243; zoom_hover=&#8220;on&#8220; display_gallery_categories=&#8220;on&#8220; gallery_categories=&#8220;27,28,29,30,249&#8243; gallery_categories_all_text=&#8220;All&#8220; paginate_gallery=&#8220;load_more&#8220; page_size=&#8220;12&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/dmg_masonry_gallery][dsm_content_timeline dsm_card_arrow=&#8220;on&#8220; dsm_image_lightbox=&#8220;on&#8220; dsm_bg_color=&#8220;RGBA(255,255,255,0)&#8220; dsm_pointer_bg_color=&#8220;#f58026&#8243; dsm_tree_bg_color=&#8220;#000000&#8243; dsm_tree_width=&#8220;2px&#8220; dsm_icon_bg_color=&#8220;#f58025&#8243; dsm_icon_font_size=&#8220;15px&#8220; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; image_icon_custom_margin=&#8220;0px||||false|false&#8220; border_radii_card_border=&#8220;on|20px|20px|20px|20px&#8220; border_width_all_card_border=&#8220;1px&#8220; border_color_all_card_border=&#8220;#f58025&#8243; global_colors_info=&#8220;{}&#8220;][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-logo.webp&#8220; alt=&#8220;solinst canada ltd&#8220; title_text=&#8220;Solinst Canada Ltd&#8220; dsm_title=&#8220;Solinst ist geboren&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Vereinbarung mit Soil Instruments zur Gr\u00fcndung einer Niederlassung in Kanada f\u00fcr den Wiederverkauf von geotechnischen Instrumenten<\/li>\n<li>Der Name &apos;Solinst&apos; wurde aus der Telex-Abk\u00fcrzung f\u00fcr Soil Instruments %22sol inst%22 gew\u00e4hlt.<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1975&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_text_color=&#8220;#000000&#8243; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1975-1988-38.webp&#8220; title_text=&#8220;1975-1988-38&#8243; dsm_title=&#8220;102 Wasserstandsanzeige&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Modell 102 Koaxialkabel-Wasserstandsmessger\u00e4t Produktion gestartet<\/li>\n<li>Hauptschwerpunkt ist der Wiederverkauf von geotechnischen Instrumenten<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1978&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1975-1988-18.webp&#8220; title_text=&#8220;1975-1988-18&#8243; dsm_title=&#8220;B\u00fcro Burlington&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Douglas Belshaw \u00fcbernimmt eine kleine Industrieanlage in Burlington Ontario.<\/li>\n<li>Beginn der Lieferung unserer charakteristischen roten Spulen f\u00fcr Wasserstandsmessger\u00e4te<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1980&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1975-1988-34.webp&#8220; title_text=&#8220;1975-1988-34&#8243; dsm_title=&#8220;Engineering Scale 101 Wasserstandsmessger\u00e4t&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Einf\u00fchrung des Wasserstandsmessers Modell 101 mit dem ersten flexiblen flachen Polyethylenband mit technischer Skala.<\/li>\n<li>Beginn der engen Zusammenarbeit mit der University of Waterloo und Dr. John Cherry<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1982&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1975-1988-7.webp&#8220; title_text=&#8220;1975-1988-7&#8243; dsm_title=&#8220;401 Waterloo Mehrstufiges System&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Beginn der Herstellung und Vermarktung des Modells 401 Waterloo Multilevel Monitoring System<\/li>\n<li>Jean Belshaw hat das Branding und das Logo unseres Unternehmens entworfen und entwickelt, w\u00e4hrend sie gleichzeitig als Marketing-Professorin am Sheridan College arbeitet.<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1984&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1989-1993-69.webp&#8220; title_text=&#8220;1989-1993-69&#8243; dsm_title=&#8220;Unternehmensschwerpunkt wechselt von Geotechnik zu Grundwasser&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Zusammenarbeit mit der University of Waterloo bei der Markteinf\u00fchrung des Modells 411 Saturated Sand Sampler<\/li>\n<li>Beginn der Verlagerung des Schwerpunkts von geotechnischen zu Grundwasser\u00fcberwachungsinstrumenten<\/li>\n<li>Jim Pianosi als erster Hydrogeologe im Vertrieb eingestellt<\/li>\n<li>Sarah Belshaw wird eingestellt, um Arbeitsabl\u00e4ufe zu entwickeln und zu verwalten<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1987&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1989-1993-13.webp&#8220; title_text=&#8220;1989-1993-13&#8243; dsm_title=&#8220;B\u00fcrostandort verschiebt sich zu Glen Williams&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Umzug vom urspr\u00fcnglichen B\u00fcro in Burlington, Ontario, nach Glen Williams %22The Williams Mill%22, (5.000 Quadratfu\u00df)<\/li>\n<li>Das Modell 615 Drive Point Piezometer kommt auf den Markt und f\u00fchrt zur Entwicklung von Edelstahl-Doppelventilpumpen, Bailern und diskreten Intervallprobennehmern<\/li>\n<li>Jim Pianosi zum Sales Manager &amp; Assistant General Manager bef\u00f6rdert<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1989&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1975-1988-26.webp&#8220; title_text=&#8220;1975-1988-26&#8243; dsm_title=&#8220;Erlangte Solinst-Patente&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Solinst erh\u00e4lt US-Patente f\u00fcr das Modell 501 Well Casing Depth Indicator und das Modell 421 VOA Trap Sampler<\/li>\n<li>Solinst-Videos, die f\u00fcr das Waterloo-Multilevel-System Modell 401 und den Sand-Bentonit-Injektor Modell 561 entwickelt wurden (VHS NTSC; PAL; SECAM Vertriebsformate)<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1990&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1989-1993-35.webp&#8220; title_text=&#8220;1989-1993-35&#8243; dsm_title=&#8220;7000 Quadratmeter f\u00fcr Produktion und Lagerung hinzugef\u00fcgt&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Zus\u00e4tzliches Kellergeschoss f\u00fcr die Produktion und Lagerung des Waterloo Systems. (7.000 Quadratfu\u00df) <\/li>\n<li>Solinst erh\u00e4lt US-Patente f\u00fcr Umweltsonde Modell 101 P4<\/li>\n<li>Sarah Belshaw zum Sales &amp; Technical Representative bef\u00f6rdert<\/li>\n<li>Modell 415 In-Situ Bioremediation Test Monitor freigegeben<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1991&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1989-1993-82.webp&#8220; title_text=&#8220;1989-1993-82&#8243; dsm_title=&#8220;Erweiterung der Maschinenhalle um 7.000 sq ft&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Anmietung zus\u00e4tzlicher Fl\u00e4che f\u00fcr eine gr\u00f6\u00dfere Maschinenhalle (7.000 Quadratfu\u00df)<\/li>\n<li>Einf\u00fchrung der Blasenpumpe Modell 405<\/li>\n<li>Modell 412 Bodenkernentnahmeger\u00e4t ver\u00f6ffentlicht<\/li>\n<li>Modell 690 Sand Piper ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1992&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1989-1993-30.webp&#8220; title_text=&#8220;1989-1993-30&#8243; dsm_title=&#8220;Solinst erwirbt kombinierte CNC-Fr\u00e4se &#8211; 1 von 3 in Nordamerika!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Vergr\u00f6\u00dferung der Produktions- und Lagerfl\u00e4che auf 11.000 Quadratfu\u00df am Standort Williams Mill<\/li>\n<li>Erste CNC-Anschaffung zur Verbesserung der Fertigungsm\u00f6glichkeiten. Kombinierte CNC-Fr\u00e4s- und Drehmaschine &#8211; eine von nur 3 in Nordamerika zu dieser Zeit! <\/li>\n<li>Solinst erh\u00e4lt US-Patente f\u00fcr die Konstruktion des Schnittstellenmessger\u00e4ts Modell 121 sowie f\u00fcr das Waterloo Multilevel System Joint (doppelter O-Ring) und den Bentonite Infill Packer<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1993&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-84.webp&#8220; title_text=&#8220;1994-2003-84&#8243; dsm_title=&#8220;Solinst zieht nach Georgetown um&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Der Kauf von 35 Todd Rd. bietet Geb\u00e4ude und Land f\u00fcr zuk\u00fcnftiges Wachstum. (24.000 Quadratfu\u00df) <\/li>\n<li>C4\/T4 Leitf\u00e4higkeits- und Temperaturprofilierungsh\u00fclsen f\u00fcr das Modell 101 P4 Wasserstandsmessger\u00e4t freigegeben<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1994&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-73.webp&#8220; title_text=&#8220;1994-2003-73&#8243; dsm_title=&#8220;Bentonit Packer Patent&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Solinst erh\u00e4lt US-Patente f\u00fcr Flexible Borehole Seal Device und Bentonitpacker Modell 401<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1995&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-38.webp&#8220; title_text=&#8220;1994-2003-38&#8243; dsm_title=&#8220;Levelogger auf den Markt gebracht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neuer OEM Levelogger, Modell 3001. Der erste kombinierte Absolutdrucksensor und Datenlogger in der Industrie. <\/li>\n<li>Neue ergonomische Solinst-Rolle aus eigener Entwicklung<\/li>\n<li>Solinst erh\u00e4lt US-Patente f\u00fcr Sand-Bentonit-Injektor und Spritzenentnahmeger\u00e4t<\/li>\n<li>Solinst.com geht online<br \/>56K Baud Internetverbindung<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1996&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-1.webp&#8220; title_text=&#8220;1994-2003-1&#8243; dsm_title=&#8220;403 CMT Multilevel System freigegeben&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Kauf einer zweiten CNC-Drehmaschine (Hitachi Seiki HT) zur Erh\u00f6hung der Produktionskapazit\u00e4t<\/li>\n<li>Schnittstellenmessger\u00e4t Modell 122 und Schlauchpumpe Modell 410 freigegeben<\/li>\n<li>Modell 403 CMT Multilevel System auf dem Markt eingef\u00fchrt<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;1998&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-104.webp&#8220; title_text=&#8220;1994-2003-104&#8243; dsm_title=&#8220;Solinst wird 25 Jahre alt!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>25 Jahre im Gesch\u00e4ft<\/li>\n<li>Sarah Belshaw zur Vizepr\u00e4sidentin bef\u00f6rdert<\/li>\n<li>Solinst erh\u00e4lt Patent f\u00fcr Reelogger Modell 2001 Multiparameter-Sonde<\/li>\n<li>Emitter produziert f\u00fcr die Universit\u00e4t von Waterloo<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2000&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-41.webp&#8220; title_text=&#8220;1994-2003-41&#8243; dsm_title=&#8220;9100 STS Telemetrie Freigegeben&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Das erste von 400 STS-Telemetriesystemen, die f\u00fcr die Verwendung mit Solinst Leveloggern entwickelt wurden, wird an das MOE (Ontario Ministry of Environment &#8211; PGMN) geliefert.<\/li>\n<li>Solinst erh\u00e4lt US-Patent f\u00fcr doppeltwirkenden CMT-Packer<\/li>\n<li>Modell 9100 STS Solinst Telemetriesystem ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2001&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/1994-2003-56.webp&#8220; title_text=&#8220;1994-2003-56&#8243; dsm_title=&#8220;Solinst expandiert&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Abschluss der Erweiterung der Todd Road Anlage (35.000 Quadratfu\u00df)<\/li>\n<li>Jean Belshaw &#8211; Pr\u00e4sident<\/li>\n<li>Solinst erh\u00e4lt US-Patent f\u00fcr CMT-Bentonitpacker<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2003&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2024\/10\/levents-1994-to-2003-booth-11.webp&#8220; title_text=&#8220;levents-1994-to-2003-booth-11&#8243; dsm_title=&#8220;US-Patent f\u00fcr CMT-Gleitringdichtungen&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Modell 107 TLC Meter ver\u00f6ffentlicht<\/li>\n<li>Einf\u00fchrung der Mikro-Doppelventilpumpe Modell 408M<\/li>\n<li>CMT Installateurschulung initiiert<\/li>\n<li>Solinst erh\u00e4lt US-Patent f\u00fcr CMT mechanische Steckerdichtungen<\/li>\n<li>Schmales 3-Kanal CMT Multilevel System ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2004&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-11.webp&#8220; title_text=&#8220;2004-2012-11&#8243; dsm_title=&#8220;Levelogger Gold von Solinst ver\u00f6ffentlicht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Solinst feiert sein 30-j\u00e4hriges Bestehen mit einer neuen 3-Jahres-Garantie f\u00fcr alle Solinst-Produkte<\/li>\n<li>Sarah Belshaw wird zur Pr\u00e4sidentin von Solinst<\/li>\n<li>Jean Belshaw wird Vorsitzender von Solinst<\/li>\n<li>Jim Pianosi zum General Manager bef\u00f6rdert<\/li>\n<li>Einf\u00fchrung des von Solinst entwickelten und hergestellten Levelogger Gold<\/li>\n<li>1. %22On The Level%22 Newsletter<\/li>\n<li>Freigegeben Solinst Modell 703 Waterloo Emitter<\/li>\n<li>800 Niederdruckpacker freigegeben<\/li>\n<li>Neuer Leveloader 2 mit USB ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2005&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-32.webp&#8220; title_text=&#8220;2004-2012-32&#8243; dsm_title=&#8220;Levelogger Serie wird erweitert&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Levelogger Junior ver\u00f6ffentlicht<\/li>\n<li>Neue peristaltische Pumpe ver\u00f6ffentlicht<\/li>\n<li>Leveloader Gold Daten\u00fcbertragungsger\u00e4t ver\u00f6ffentlicht<\/li>\n<li>Solinst erh\u00e4lt US-Patent f\u00fcr 3-Kanal CMT<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2007&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-51.webp&#8220; title_text=&#8220;2004-2012-51&#8243; dsm_title=&#8220;3002 Rainlogger ver\u00f6ffentlicht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>SDI-12 Protokoll aktiviert f\u00fcr Levelogger Serie<\/li>\n<li>Modell 3002 Rainlogger ver\u00f6ffentlicht<\/li>\n<li>STS Gold Telemetriesystem ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2008&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2024\/10\/events-2004-to-2012-9-scaled.webp&#8220; title_text=&#8220;events-2004-to-2012-9&#8243; dsm_title=&#8220;Solinst betritt das Laserzeitalter!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>1. Solinst-Symposium %22Neueste Fortschritte in der \u00dcberwachung von Wassereinzugsgebieten und hoher Aufl\u00f6sung%22<\/li>\n<li>Neue Laserbeschriftungsmaschine, selbst entworfen und entwickelt<\/li>\n<li>Neuer LTC Levelogger Junior ver\u00f6ffentlicht<\/li>\n<li>9200 RRL Funkfernverbindung<\/li>\n<li>Lasermarkiertes Modell 102 Wasserstandsmessger\u00e4t und Modell 103 Tag Line freigegeben<\/li>\n<li>Neues elektronisches Pumpensteuerger\u00e4t 464 ver\u00f6ffentlicht<\/li>\n<li>Neuer Solinst.com-Umbau Version 5 abgeschlossen<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2009&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-1.webp&#8220; title_text=&#8220;2004-2012-1&#8243; dsm_title=&#8220;Neu 101 P7 Wasserstandsmessger\u00e4t&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neues 101 P7 Wasserstandsmessger\u00e4t mit lasermarkiertem PVDF-Flachband erschienen<\/li>\n<li>Levelogger der n\u00e4chsten Generation, Modell 3001 Edge, mit komplett neuem Design<\/li>\n<li>Solinst geformte Brunnenkappen f\u00fcr Levelogger und Probenehmer<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2011&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-5.webp&#8220; title_text=&#8220;2004-2012-5&#8243; dsm_title=&#8220;107 TLC Messger\u00e4t komplett neu gestaltet&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neuer Levelogger Junior Edge ver\u00f6ffentlicht<\/li>\n<li>Laserbeschriftetes 107 TLC Messger\u00e4t, komplett neu gestaltet<\/li>\n<li>Erstes Solinst YouTube Video TLC Meter Benutzerkalibrierung<\/li>\n<li>Die neue 101 Power Reel mit mehr Leistung f\u00fcr gr\u00f6\u00dfere L\u00e4ngen<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2012&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/2004-2012-6.webp&#8220; title_text=&#8220;2004-2012-6&#8243; dsm_title=&#8220;Neues Interface Messger\u00e4t ver\u00f6ffentlicht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neues 122 \u00d6l\/Wasser-Schnittstellenmessger\u00e4t ver\u00f6ffentlicht<\/li>\n<li>103 Tag Line mit laserbeschriftetem, flachem Klebeband ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2013&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001appinthhero.jpg&#8220; title_text=&#8220;3001appinthhero&#8220; dsm_title=&#8220;Solinst ver\u00f6ffentlicht 1. mobile App!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neue Solinst Levelogger App f\u00fcr iOS ver\u00f6ffentlicht<\/li>\n<li>Neue Version des 122M Mini Oil \/ Water Interface Meter ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2014&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-datagrabber-usb.jpg&#8220; title_text=&#8220;3001-datagrabber-usb&#8220; dsm_title=&#8220;DataGrabber ver\u00f6ffentlicht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Levelogger App f\u00fcr Android ver\u00f6ffentlicht<\/li>\n<li>Neuer DataGrabber f\u00fcr Levelogger ver\u00f6ffentlicht<\/li>\n<li>102 Wasserstandsmesssonden neu gestaltet<\/li>\n<li>3001 Artesischer Brunnen Fitting freigegeben<\/li>\n<li>Neues preiswertes Wasserstandsmessger\u00e4t 101B ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2015&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/9500-levelsender-main.png&#8220; title_text=&#8220;9500-levelsender-main&#8220; dsm_title=&#8220;LevelSender Telemetrie auf den Markt gebracht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>3500 AquaVent Bel\u00fcfteter Datenlogger ver\u00f6ffentlicht<\/li>\n<li>Neues LevelSender Telemetriesystem 9500 ver\u00f6ffentlicht<\/li>\n<li>Jim Pianosi zum Pr\u00e4sidenten bef\u00f6rdert<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2016&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-ltc-edge-right-2x.jpg&#8220; title_text=&#8220;3001-ltc-edge-right-2x&#8220; dsm_title=&#8220;Levelogger LTC Edge ver\u00f6ffentlicht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>201 Wasserstand Temperaturmesser freigegeben<\/li>\n<li>3001 LTC Levelogger Edge freigegeben<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2017&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2024\/11\/410-peristaltic-pump.webp&#8220; alt=&#8220;solinst model 410 peristaltic pump&#8220; title_text=&#8220;Solinst Model 410 Peristaltic Pump&#8220; dsm_title=&#8220;Neues Design der 410er Peristaltikpumpe vorgestellt!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>101D Wasserstandsabsauger freigegeben<\/li>\n<li>Neuer 3250 LevelVent Wasserstands-Datenlogger ver\u00f6ffentlicht<\/li>\n<li>Neu gestaltete 410 Schlauchpumpe ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2018&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2024\/10\/105-well-casing-and-depth-indicator-1-500&#215;500-1.webp&#8220; alt=&#8220;solinst 105 well casing and depth indicator&#8220; title_text=&#8220;Solinst 105 Well Casing And Depth Indicator&#8220; dsm_title=&#8220;Solinst f\u00fchrt den 105 Well Casing &amp; Depth Indicator mit neuem Design wieder ein&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neue 3D-gedruckte 12V Peristaltikpumpe mit Batteriehalterung ver\u00f6ffentlicht<\/li>\n<li>\u00dcberarbeitetes 105er Bohrlochgeh\u00e4use und Tiefenmesser ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2019&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-absolute-water-level-datalogging.webp&#8220; alt=&#8220;absolute water level datalogging&#8220; title_text=&#8220;Absolute Water Level Datalogging&#8220; dsm_title=&#8220;Levelogger 5 auf den Markt gebracht&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Neu 102 Wasserstandsmessger\u00e4t mit Lasermarkierung Gelbes Kabel freigegeben<\/li>\n<li>Neue Levelogger 5-Serie mit neuem Levelogger-Design und verbesserter optischer Verbindung<\/li>\n<li>Mike Hughes zum General Manager bef\u00f6rdert<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2020&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2024\/09\/425-discrete-interval-sampler-thumbnail-234&#215;232-1.webp&#8220; alt=&#8220;solinst model 425 discrete interval sampler&#8220; title_text=&#8220;Solinst Model 425 Discrete Interval Sampler&#8220; dsm_title=&#8220;Der neue Deep Discrete Interval Sampler erreicht 1200 m mit einer Fahrradpumpe!&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>104 Sonic Water Level Meter ver\u00f6ffentlicht<\/li>\n<li>Neue tragbare Feldtabellen ver\u00f6ffentlicht<\/li>\n<li>425D Deep Discrete Interval Sampler ver\u00f6ffentlicht<\/li>\n<li>615ML Multilevel Drive Point Piezometer ver\u00f6ffentlicht<\/li>\n<li>Plug and Play 4G LevelSender 5 Telemetrie mit integrierter SIM-Karte ver\u00f6ffentlicht<\/li>\n<li>4001 SRU Solinst-Ausleseeinheit freigegeben<\/li>\n<li>800M Mini Pneumatischer Packer ver\u00f6ffentlicht<\/li>\n<li>415 12V Unterwasserpumpe freigegeben<\/li>\n<li>101 Power Winder ver\u00f6ffentlicht<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2021&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/9700-solsat-discover-anywhere-monitoring.webp&#8220; title_text=&#8220;SolSat 5 Satellite Telemetry System Discover Anywhere Monitoring&#8220; dsm_title=&#8220;Entdecken Sie Anywhere Monitoring&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>301 Wasserstands-Temperatursensor freigegeben<\/li>\n<li>9700 SolSat 5 Satellitentelemetriesystem ver\u00f6ffentlicht (Discover Anywhere Monitoring)<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2023&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-flute-logo-600w.webp&#8220; alt=&#8220;solinst flute&#8220; title_text=&#8220;Solinst Flute&#8220; dsm_title=&#8220;Solinst Flute wird Mitglied der Solinst Familie&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Solinst Cloud zur Vereinfachung der \u00dcberwachung, Erweiterung von Netzwerken und Ausbau der Datenverwaltung<\/li>\n<li>Neu gestaltete Blasenpumpe 407 mit leicht austauschbaren Kartuschen ver\u00f6ffentlicht<\/li>\n<li>4-20mA mit Stromschleifenadapter freigegeben f\u00fcr 301 Wasserstand-Temperatursensor<\/li>\n<li>Solinst Field Services Abteilung geht an den Start<\/li>\n<li>FLUTe wird von Solinst Canada Ltd. \u00fcbernommen. Solinst Flute wird Mitglied der Solinst Familie. <\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2024&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-logo-800w.webp&#8220; alt=&#8220;solinst eureka logo&#8220; title_text=&#8220;Solinst Eureka Logo&#8220; dsm_title=&#8220;Solinst Eureka wird Mitglied der Solinst Familie&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Eureka Water Probes Acquired by Solinst Canada Ltd.<br \/>Solinst Eureka wird Mitglied der Solinst Familie.<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2025&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/01\/101D-410-news.webp&#8220; alt=&#8220;new solinst 410 peristaltic pump mk5 and 101d water level drawdown meter with drawdown cable link connection&#8220; title_text=&#8220;New Solinst 410 Peristaltic Pump Mk5 version with 101D Water Level DrawDown Meter with DrawDown Cable Link Connection&#8220; dsm_title=&#8220;Grundwasserprobenahme wird automatisiert&#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li>Das aktualisierte 101D Water Level DrawDown Meter stoppt\/startet die peristaltische Pumpe Mk5 410 bei Echtzeit-Wasserstand<\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2026&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][dsm_content_timeline_child dsm_image=&#8220;https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-ltd.webp&#8220; alt=&#8220;solinst uk ltd&#8220; title_text=&#8220;Solinst UK Ltd&#8220; dsm_title=&#8220;Solinst UK Ltd. B\u00fcro bekannt gegeben &#8220; dsm_content=&#8220;<\/p>\n<ul>\n<li><span>Wir sind<\/span><span> <\/span><span>zufrieden<\/span><span> <\/span><span>zu<\/span><span> <\/span><span>Aktie<\/span><span> <\/span><span>dass<\/span><span> <\/span><span>Solinst<\/span><span> <\/span><span>hat<\/span><span> <\/span><span>ge\u00f6ffnet<\/span><span> <\/span><span>a<\/span><span> <\/span><span>neu<\/span><span> <\/span><span>B\u00fcro<\/span><span> <\/span><span>zu<\/span><span> <\/span><span>anbieten.<\/span><span> <\/span><span>direkt<\/span><span> <\/span><span>Verkauf<\/span><span> <\/span><span>und<\/span><span> <\/span><span>Unterst\u00fctzung<\/span><span> <\/span><span>f\u00fcr<\/span><span> <\/span><span>die<\/span><span> <\/span><span>Vereinigte<\/span><span> <\/span><span>K\u00f6nigreich<\/span><span> <\/span><span>und<\/span><span> <\/span><span>Irland<\/span><span>.<\/span><span> <\/span><span>Die<\/span><span> <\/span><span>Einrichtung<\/span><span> <\/span><span>von<\/span><span> <\/span><span>Solinst<\/span><span> <\/span><span>UK<\/span><span> <\/span><span>Ltd<\/span><span> <\/span><span>in<\/span><span> <\/span><span>die<\/span><span> <\/span><span>West<\/span><span> <\/span><span>Mittelland<\/span><span> <\/span><span>wird<\/span><span> <\/span><span>geben.<\/span><span> <\/span><span>Kunden<\/span><span> <\/span><span>mehr<\/span><span> <\/span><span>Zugang<\/span><span> <\/span><span>zu<\/span><span> <\/span><span>unser<\/span><span> <\/span><span>erfahren<\/span><span> <\/span><span>Solinst<\/span><span> <\/span><span>Team<\/span><span>.<\/span><\/li>\n<\/ul>\n<p>&#8220; dsm_use_pointer_element=&#8220;on&#8220; dsm_point_font_icon=&#8220;&#x22;||divi||400&#8243; dsm_opposite_text=&#8220;2026&#8243; _builder_version=&#8220;4.27.6&#8243; _module_preset=&#8220;default&#8220; header_level=&#8220;h2&#8243; header_font=&#8220;|700|||||||&#8220; opposite_text_font=&#8220;|700|||||||&#8220; opposite_text_font_size=&#8220;30px&#8220; global_colors_info=&#8220;{}&#8220; parent_header_level=&#8220;h4&#8243;][\/dsm_content_timeline_child][\/dsm_content_timeline][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]Solinst Canada Ltd. stellt seit 1980 hochwertige Grundwasser-Messger\u00e4te her. Damals erkannte der Pr\u00e4sident des Unternehmens, Doug Belshaw, den Bedarf an innovativen und einfach zu bedienenden Messger\u00e4ten f\u00fcr den wachsenden Bereich der Hydrogeologie.<\/p>\n<p>Zuerst f\u00fchrte Solinst sein <strong><a href=\"https:\/\/www.solinst.com\/de\/produkte\/solinst-eureka\/robuste-feldgeraete-und-apps\/mantamobil\/mantamobile-datenblatt\/\" title=\"Modell 101 Wasserstandsmessger\u00e4t\">Wasserstandsmessger\u00e4t Modell 101<\/a><\/strong> f\u00fcr Hydrogeologen in den Vereinigten Staaten ein. Die robuste Konstruktion, das dehnungsbest\u00e4ndige Band und die speziellen Markierungen in Fu\u00df und Zehntel-Fu\u00df (jetzt 1\/100 ft) erwiesen sich als ideal. Das Messger\u00e4t gewann an Popularit\u00e4t und wurde bald zum Wasserstandsmessger\u00e4t der Wahl f\u00fcr die amerikanische Grundwasser\u00fcberwachung.<\/p>\n<p>Seitdem haben harte Arbeit, ein offenes Ohr f\u00fcr unsere Kunden und kreatives Denken Solinst zum Aufbl\u00fchen gebracht. Heute bieten wir eine breite Palette innovativer und praktischer Ger\u00e4te an, die sowohl von Hydrogeologen als auch von Hydrologen auf der ganzen Welt eingesetzt werden. Das Angebot umfasst nach wie vor Wasserstandsmessger\u00e4te, hat sich aber um Datenlogger, Telemetrie, Schnittstellenmessger\u00e4te, Drive-Points, Probenehmer und Multilevel-Systeme erweitert.[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;0px||0px||false|false&#8220; custom_padding=&#8220;0px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;3_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/about-us-article.webp\" width=\"1178\" height=\"1044\" alt=\"Zeitungsartikel \u00fcber Solinst\" class=\"wp-image-32408 alignnone size-full\" srcset=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/about-us-article.webp 1178w, https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/about-us-article-980x869.webp 980w, https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/about-us-article-480x425.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1178px, 100vw\" \/><\/p>\n<p><strong><em>Ein wenig Geschichte &#8211; obiger Artikel erschien am 1. Mai 1991 in der lokalen Zeitung von Georgetown \/ Acton Ontario Canada \u00fcber den Einsatz von Solinst-Ger\u00e4ten bei einem Reifenbrand.<\/em><\/strong><\/p>\n<p>Die Solinst-Produktlinie ist ideal f\u00fcr Standortcharakterisierungen, Untersuchungen von Leckagen und langfristige Grundwasser\u00fcberwachung.<\/p>\n<p>Hinter der gesamten Palette der hochwertigen Grundwasser\u00fcberwachungsger\u00e4te von Solinst steht das geballte Fachwissen von erfahrenen Hydrogeologen, geotechnischen Ingenieuren, Fertigungs- und Elektronikfachleuten und Technikern.<\/p>\n<p>Solinst widmet sich der Herstellung von qualitativ hochwertigen Instrumenten, die auf Genauigkeit, Benutzerfreundlichkeit und langfristig zuverl\u00e4ssige Ergebnisse ausgelegt sind.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Adobe Analytics Code&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_code admin_label=&#8220;AA Code f\u00fcr diese Seite&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<!-- SiteCatalyst code version: H.21. Copyright 1996-2010 Adobe, Inc. All Rights Reserved More info available at http:\/\/www.omniture.com --><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\" src=\"\/\/www.solinst.com\/s_code.js\"><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->s.pageName=\"about\"<!-- [et_pb_line_break_holder] -->s.server=\"\"<!-- [et_pb_line_break_holder] -->s.channel=\"about\"<!-- [et_pb_line_break_holder] -->s.pageType=\"\"<!-- [et_pb_line_break_holder] -->s.prop1=\"\"<!-- [et_pb_line_break_holder] -->s.prop2=\"\"<!-- [et_pb_line_break_holder] -->s.prop3=\"\"<!-- [et_pb_line_break_holder] -->s.prop4=\"\"<!-- [et_pb_line_break_holder] -->s.prop5=\"\"<!-- [et_pb_line_break_holder] -->s.prop6=\"\"<!-- [et_pb_line_break_holder] -->s.prop7=\"\"<!-- [et_pb_line_break_holder] -->s.prop8=\"\"<!-- [et_pb_line_break_holder] -->s.prop9=\"\"<!-- [et_pb_line_break_holder] -->s.prop10=\"\"<!-- [et_pb_line_break_holder] -->s.prop11=\"\"<!-- [et_pb_line_break_holder] -->s.prop12=\"\"<!-- [et_pb_line_break_holder] -->s.prop13=\"\"<!-- [et_pb_line_break_holder] -->s.prop14=\"\"<!-- [et_pb_line_break_holder] -->s.prop15=\"\"<!-- [et_pb_line_break_holder] -->s.prop16=\"\"<!-- [et_pb_line_break_holder] -->s.prop17=\"\"<!-- [et_pb_line_break_holder] -->s.prop18=\"\"<!-- [et_pb_line_break_holder] -->s.prop19=\"\"<!-- [et_pb_line_break_holder] -->s.prop20=\"\"<!-- [et_pb_line_break_holder] -->s.prop21=\"\"<!-- [et_pb_line_break_holder] -->s.prop22=\"\"<!-- [et_pb_line_break_holder] -->s.prop23=\"\"<!-- [et_pb_line_break_holder] -->s.prop24=\"\"<!-- [et_pb_line_break_holder] -->s.prop25=\"\"<!-- [et_pb_line_break_holder] -->s.prop26=\"\"<!-- [et_pb_line_break_holder] -->s.prop27=\"\"<!-- [et_pb_line_break_holder] -->s.prop28=\"\"<!-- [et_pb_line_break_holder] -->s.prop29=\"\"<!-- [et_pb_line_break_holder] -->s.prop30=\"\"<!-- [et_pb_line_break_holder] -->s.prop31=\"\"<!-- [et_pb_line_break_holder] -->s.prop32=\"\"<!-- [et_pb_line_break_holder] -->s.prop33=\"\"<!-- [et_pb_line_break_holder] -->s.hier1=\"solinst:about\"<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/* Conversion Variables *\/<!-- [et_pb_line_break_holder] -->s.campaign=\"\"<!-- [et_pb_line_break_holder] -->s.events=\"\"<!-- [et_pb_line_break_holder] -->s.eVar1=\"\"<!-- [et_pb_line_break_holder] -->s.eVar2=\"\"<!-- [et_pb_line_break_holder] -->s.eVar3=\"\"<!-- [et_pb_line_break_holder] -->s.eVar4=\"\"<!-- [et_pb_line_break_holder] -->s.eVar5=\"\"<!-- [et_pb_line_break_holder] -->s.eVar6=\"\"<!-- [et_pb_line_break_holder] -->s.eVar7=\"\"<!-- [et_pb_line_break_holder] -->s.eVar8=\"\"<!-- [et_pb_line_break_holder] -->s.eVar9=\"\"<!-- [et_pb_line_break_holder] -->s.eVar10=\"\"<!-- [et_pb_line_break_holder] -->s.eVar11=\"\"<!-- [et_pb_line_break_holder] -->s.eVar12=\"\"<!-- [et_pb_line_break_holder] -->s.eVar13=\"\"<!-- [et_pb_line_break_holder] -->s.eVar14=\"\"<!-- [et_pb_line_break_holder] -->s.eVar15=\"\"<!-- [et_pb_line_break_holder] -->s.eVar16=\"\"<!-- [et_pb_line_break_holder] -->s.eVar17=\"\"<!-- [et_pb_line_break_holder] -->s.state=\"\"<!-- [et_pb_line_break_holder] -->s.zip=\"\"<!-- [et_pb_line_break_holder] -->\/************* DO NOT ALTER ANYTHING BELOW THIS LINE ! **************\/<!-- [et_pb_line_break_holder] -->var s_code=s.t();if(s_code)document.write(s_code)\/\/--><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->if(navigator.appVersion.indexOf('MSIE')>=0)document.write(unescape('%3C')+'!-'+'-')<!-- [et_pb_line_break_holder] -->\/\/--><\/script><noscript><a href=\"https:\/\/www.omniture.com\" title=\"Webanalyse\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solinst.d2.sc.omtrdc.net\/b\/ss\/solinst-prod\/1\/H.21--NS\/0\" height=\"1\" width=\"1\" border=\"0\" alt=\"\"><\/a><\/noscript><!--\/DO NOT REMOVE\/--><!-- [et_pb_line_break_holder] --><!-- End SiteCatalyst code version: H.21. -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"https:\/\/www.solinst.com\/de\/\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"et-pb-icon dsm_home_icon\">\ue009<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\tHome\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">5<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div> &nbsp; Genaue Wasserstandsdaten Zuverl\u00e4ssige und langlebige Instrumente&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Solinst Kanada Ltd. Das 1975 gegr\u00fcndete Unternehmen Solinst hat seit langem die Vision, zuverl\u00e4ssige, qualitativ hochwertige L\u00f6sungen f\u00fcr Grundwasserfachleute auf der ganzen Welt anzubieten. Im Laufe der Jahre hat sich das Unternehmen zu einem angesehenen Branchenf\u00fchrer entwickelt, der f\u00fcr seine innovativen Produkte und sein Engagement f\u00fcr die Weiterentwicklung der Wasser\u00fcberwachungstechnologie bekannt ist. Solinst begann in einem kleinen Industriegeb\u00e4ude in Burlington, Ontario, und befindet sich heute in einer gro\u00dfen Anlage in Georgetown, Ontario, und ist weiterhin ein erfolgreiches Unternehmen im Besitz der Familie Belshaw. Solinst ist stolz darauf, dass alles im eigenen Haus gemacht wird, vom Design, der Entwicklung und der Produktion bis hin zum technischen Verkaufssupport und Kundendienst. Im Laufe seiner Geschichte hat Solinst seine Produktlinie kontinuierlich erweitert und bietet eine Reihe von Instrumenten an, die auf Pr\u00e4zision und Langlebigkeit ausgelegt sind. Vom kultigen Wasserstandsmessger\u00e4t Modell 101 bis hin zur fortschrittlichen Levelogger-Serie sind die Instrumente von Solinst zu unverzichtbaren Werkzeugen f\u00fcr Hydrogeologen, Umweltberater und Wasserressourcenmanager auf der ganzen Welt geworden. Das Engagement des Unternehmens f\u00fcr Innovationen wird auch durch die j\u00fcngste \u00dcbernahme von Flexible Liner Underground Technologies (jetzt Solinst Flute), die das Unternehmen in die [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":32376,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"folder":[233],"class_list":["post-32011","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00dcber Solinst Canada Ltd<\/title>\n<meta name=\"description\" content=\"\u00dcber Solinst Canada Ltd. Solinst stellt hochwertige Instrumente zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser her.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solinst.com\/de\/ueber\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solinst Canada Ltd - \u00dcber uns\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die Geschichte und Innovation von Solinst Canada Ltd., einem f\u00fchrenden Hersteller von hochwertigen Instrumenten zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solinst.com\/de\/ueber\/\" \/>\n<meta property=\"og:site_name\" content=\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T21:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/feature-about-us-article.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Solinst Canada Ltd - \u00dcber uns\" \/>\n<meta name=\"twitter:description\" content=\"Entdecken Sie die Geschichte und Innovation von Solinst Canada Ltd., einem f\u00fchrenden Hersteller von hochwertigen Instrumenten zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser.\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"29\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/\",\"name\":\"\u00dcber Solinst Canada Ltd\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/feature-about-us-article.jpg\",\"datePublished\":\"2025-01-14T22:00:37+00:00\",\"dateModified\":\"2026-05-05T21:39:11+00:00\",\"description\":\"\u00dcber Solinst Canada Ltd. Solinst stellt hochwertige Instrumente zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser her.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/feature-about-us-article.jpg\",\"contentUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/feature-about-us-article.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/ueber\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00dcber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/\",\"name\":\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\",\"description\":\"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solinst.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00dcber Solinst Canada Ltd","description":"\u00dcber Solinst Canada Ltd. Solinst stellt hochwertige Instrumente zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser her.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solinst.com\/de\/ueber\/","og_locale":"de_DE","og_type":"article","og_title":"Solinst Canada Ltd - \u00dcber uns","og_description":"Entdecken Sie die Geschichte und Innovation von Solinst Canada Ltd., einem f\u00fchrenden Hersteller von hochwertigen Instrumenten zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser.","og_url":"https:\/\/www.solinst.com\/de\/ueber\/","og_site_name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","article_modified_time":"2026-05-05T21:39:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/feature-about-us-article.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Solinst Canada Ltd - \u00dcber uns","twitter_description":"Entdecken Sie die Geschichte und Innovation von Solinst Canada Ltd., einem f\u00fchrenden Hersteller von hochwertigen Instrumenten zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser.","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"29\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.solinst.com\/de\/ueber\/","url":"https:\/\/www.solinst.com\/de\/ueber\/","name":"\u00dcber Solinst Canada Ltd","isPartOf":{"@id":"https:\/\/www.solinst.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solinst.com\/de\/ueber\/#primaryimage"},"image":{"@id":"https:\/\/www.solinst.com\/de\/ueber\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/feature-about-us-article.jpg","datePublished":"2025-01-14T22:00:37+00:00","dateModified":"2026-05-05T21:39:11+00:00","description":"\u00dcber Solinst Canada Ltd. Solinst stellt hochwertige Instrumente zur \u00dcberwachung von Grund- und Oberfl\u00e4chenwasser her.","breadcrumb":{"@id":"https:\/\/www.solinst.com\/de\/ueber\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solinst.com\/de\/ueber\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.solinst.com\/de\/ueber\/#primaryimage","url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/feature-about-us-article.jpg","contentUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/feature-about-us-article.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.solinst.com\/de\/ueber\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.solinst.com\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"\u00dcber"}]},{"@type":"WebSite","@id":"https:\/\/www.solinst.com\/de\/#website","url":"https:\/\/www.solinst.com\/de\/","name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","description":"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solinst.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/pages\/32011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/comments?post=32011"}],"version-history":[{"count":0,"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/pages\/32011\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/media\/32376"}],"wp:attachment":[{"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/media?parent=32011"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.solinst.com\/de\/wp-json\/wp\/v2\/folder?post=32011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}