{"id":121591,"date":"2025-09-04T19:37:45","date_gmt":"2025-09-04T19:37:45","guid":{"rendered":"https:\/\/www.solinst.com\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/"},"modified":"2026-06-01T16:55:57","modified_gmt":"2026-06-01T16:55:57","slug":"101d-medidor-de-descenso-del-nivel-de-agua","status":"publish","type":"page","link":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/","title":{"rendered":"101D Medidor de descenso del nivel de agua"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/101d-water-level-drawdown-meter1920x500-1.webp\u00bb alt=\u00bbmedidor de descenso del nivel de agua solinst 101d\u00bb title_text=\u00bbVista frontal del medidor de nivel de agua Solinst 101D\u00bb src_tablet=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/101d-water-level-drawdown-meter965x500-1.webp\u00bb src_phone=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/101d-water-level-drawdown-meter965x500-1.webp\u00bb src_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbH1 and breadcrumbs\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bb792ca5bd-0808-46bd-9ce7-3bcb8e74f4d3&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bb4b28f470-0d73-4e9d-b92d-e6f41f2cea24&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bb101D Medidor de descenso del nivel de agua\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb6983e4e7-a6e0-4a8d-b486-49939fd240c0&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][dsm_breadcrumbs disabled_on=\u00bbon|off|off\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb home_icon_text_color=\u00bb#d6d6d6&#8243; global_colors_info=\u00bb{}\u00bb][\/dsm_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb4759a92f-4b27-4854-bb2c-299854634e93&#8243; global_module=\u00bb121878&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bb101D Mobile Nav &#8211; Seleccionar desplegable\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_css_free_form=\u00bbselect {||||      font-size: 1em; \/* Adjust font size *\/||      padding: 10px;   \/* Optional: Increase padding for better spacing *\/||      width: 100%;||      box-sizing: border-box;\/* Optional: Adjust width to fit the container *\/||      height: 50px;||}||||    \/* Style for dropdown options (fallback if needed) *\/||select option {||      font-size: 1.2em; \/* Ensures option text matches select styling *\/||      width: 100%;||    }\u00bb global_colors_info=\u00bb{}\u00bb]<select name=\"dropdown\" onchange=\"location = this.value;\"><!-- [et_pb_line_break_holder] --><option value=\"\">101D Nivel de agua Men\u00fa de enlace del medidor DrawDown<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/\">P\u00e1gina principal del medidor de nivel de agua DrawDown<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/101-water-level-meter\/get-quote.php?prod=101d\">Pedir presupuesto<\/option><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/Forms\/sol.php\">Env\u00edame informaci\u00f3n<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/datasheet\/\">Ficha<\/option><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/\">Instrucciones<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/101d-water-level-drawdown-meter-operating-instructions\/\">-Instrucciones de uso<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/connecting-laser-marked-replacement-tape-to-reel\/\">-Conexi\u00f3n de la cinta de repuesto marcada con l\u00e1ser a la bobina<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/probe-crimp-terminal-replacement\/\">-Sustituci\u00f3n del terminal de crimpado de la sonda<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/backplate-replacement\/\">-Sustituci\u00f3n de la placa posterior<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/battery-drawer-replacement\/\">-Sustituci\u00f3n del caj\u00f3n de la bater\u00eda<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/101-water-level-meter\/operating-instructions\/101-frame-break-probe-holder-replacement.pdf\">-Sustituci\u00f3n del bastidor, el freno y el soporte de la sonda (PDF)<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/101d-water-level-drawdown-meter\/instructions\/tape-seal-plug-brass-tube-replacement\/\">-Tape Seal Plug Tubos de lat\u00f3n de repuesto<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/data\/wlm-comparison.pdf\">Cuadro comparativo de contadores (PDF)<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/data\/wlm-tape-probe-comparison.pdf\">Tabla comparativa de cintas y sondas (PDF)<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/level-measurement-devices\/\">Dispositivos de medici\u00f3n de nivel<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/lmd-comparison.php\">Tabla comparativa de dispositivos de medici\u00f3n de nivel<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/lmd-comparison-tape-probe.php\">Dispositivos de medici\u00f3n de nivel &#8211; Comparaci\u00f3n de cintas y sondas<\/option><!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] --><\/select>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; specialty=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb5a5bca26-a9a5-4e6c-8fca-d64da3bdcd40&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_menu menu_id=\u00bb404&#8243; admin_label=\u00bb101D Water Level DrawDown Meter Main Nav\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb242faa89-ac4f-4e46-90fe-505e8c1eab79&#8243; global_module=\u00bb121778&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_menu][et_pb_slider disabled_on=\u00bbon|on|off\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb display_conditions=\u00bbW10=\u00bb link_option_url=\u00bbhttps:\/\/www.solinst.com\/instruments\/dataloggers-and-telemetry-systems\/3001-levelogger\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position1&#038;utm_campaign=3001&#8243; global_module=\u00bb53188&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide button_text=\u00bbLevelogger\u00bb button_link=\u00bbhttps:\/\/www.solinst.com\/es\/productos\/registradores-de-datos-y-sistemas-de-telemetria\/3001-nivelador\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position1&amp;utm_campaign=3001&#8243; use_bg_overlay=\u00bbon\u00bb bg_overlay_color=\u00bbrgba(224,97,0,0.58)\u00bb button_text_tablet=\u00bb\u00bb button_text_phone=\u00bb\u00bb button_text_last_edited=\u00bbon|desktop\u00bb content_tablet=\u00bb\u00bb content_phone=\u00bb\u00bb content_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#F07C00&#8243; background_enable_color=\u00bbon\u00bb background_image=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-absolute-water-level-datalogging.webp\u00bb background_enable_image=\u00bbon\u00bb background_position=\u00bbtop_center\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#f58025&#8243; button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#ffffff\u00bb button_border_radius=\u00bb20px\u00bb button_font=\u00bb|600|||||||\u00bb background_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb button_border_width__hover_enabled=\u00bbon|hover\u00bb button_border_width__hover=\u00bb2px\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h2>Datos precisos sobre el nivel del agua<\/h2>\n<p><b>Instrumentos fiables y duraderos<\/b><\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][et_pb_slider disabled_on=\u00bbon|on|on\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb link_option_url=\u00bbhttps:\/\/www.solinst.com\/careers\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position2&#038;utm_campaign=SUK-regional-sales-manager\u00bb disabled=\u00bbon\u00bb global_module=\u00bb53561&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide heading=\u00bb\u00a1Solinst UK est\u00e1 contratando!\u00bb button_text=\u00bbDirector Regional de Ventas\u00bb button_link=\u00bbhttps:\/\/www.solinst.com\/careers\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position2&amp;utm_campaign=SUK-regional-sales-manager\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_text_color=\u00bb#000000&#8243; header_font_size=\u00bb38px\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb background_enable_color=\u00bbon\u00bb background_image=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-ltd.webp\u00bb background_enable_image=\u00bbon\u00bb background_size=\u00bbcontain\u00bb custom_button=\u00bbon\u00bb button_bg_color=\u00bb#f58025&#8243; button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#ffffff\u00bb button_border_radius=\u00bb20px\u00bb button_font=\u00bb|600|||||||\u00bb button_custom_margin=\u00bb||||false|false\u00bb button_custom_padding=\u00bb1px||||false|false\u00bb custom_padding=\u00bb76px||||false|false\u00bb header_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; specialty_columns=\u00bb3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbEl medidor de nivel de agua 101D DrawDown: Ahora con Control de Bomba Manos Libres y Muestreo Automatizado\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb46ad5c23-ecb8-466b-9973-452975f03683&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text admin_label=\u00bbresearch article\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb26px\u00bb header_2_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li><strong>Deje de cuidar su bomba perist\u00e1ltica.<\/strong>  El medidor de descenso del nivel de agua Solinst 101D automatiza sus pruebas de muestreo y descenso del nivel de agua para ahorrar tiempo y garantizar resultados precisos.<\/li>\n<li>Modos de nivel de agua est\u00e1tico y descenso en un metro<\/li>\n<li>Una c\u00f3moda palanca facilita el cambio entre las dos funciones<\/li>\n<li>Longitudes de cinta de hasta 1500 m (5000 pies)<\/li>\n<\/ul>\n<p>El <strong>medidor de descenso del nivel de agua modelo 101D<\/strong> es la herramienta esencial de doble funci\u00f3n en la que conf\u00edan los profesionales de campo, ahora con capacidad de automatizaci\u00f3n mejorada. Utilice el sencillo conmutador para alternar entre <strong>mediciones est\u00e1ticas del nivel de agua<\/strong> en pozos, sondeos y dep\u00f3sitos, y la <strong>monitorizaci\u00f3n de la reducci\u00f3n del nivel<\/strong> para pruebas de acu\u00edferos y pozos. Adem\u00e1s de su robusto dise\u00f1o y su precisa cinta plana marcada con l\u00e1ser, el medidor de nivel de agua 101D ofrece una nueva y potente funci\u00f3n que redefine la eficiencia sobre el terreno.[\/et_pb_text][et_pb_text disabled_on=\u00bbon|on|on\u00bb admin_label=\u00bbresearch article\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb26px\u00bb header_2_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||20px||false|false\u00bb disabled=\u00bbon\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Medidor de descenso del nivel de agua<\/strong><\/h2>\n<p><strong>2 productos en 1<\/strong><\/p>\n<ul>\n<li>Modos de nivel de agua est\u00e1tico y descenso en un metro<\/li>\n<li>Una c\u00f3moda palanca facilita el cambio entre las dos funciones<\/li>\n<li>Longitudes de cinta de hasta 1500 m (5000 pies)<\/li>\n<\/ul>\n<p>El <strong>medidor de nivel de agua 101D Draw Down Meter<\/strong>, que tiene todas las mismas caracter\u00edsticas que nuestro <strong>medidor de nivel de agua modelo 101P7<\/strong>, con el beneficio a\u00f1adido del nuevo modo Drawdown, todo en una sola unidad. Cuando est\u00e1 en el modo DrawDown la sonda se\u00f1ala en aire en lugar de agua. Esta es una gran caracter\u00edstica si usted necesita saber cuando los niveles en un pozo est\u00e1n bajando. El medidor de descenso de nivel de agua 101D tambi\u00e9n utiliza nuestra cinta plana marcada con l\u00e1ser, con longitudes est\u00e1ndar de hasta 300 m (1000 pies).   <\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/101d-water-level-drawdown-meter-facing-left-2.webp\u00bb alt=\u00bbmedidor de descenso del nivel de agua solinst 101d orientado hacia la izquierda\u00bb title_text=\u00bbSolinst 101D Medidor de nivel de agua orientado hacia la izquierda\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_button button_url=\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/101-water-level-meter\/get-quote.php?prod=101d\u00bb button_text=\u00bbObtener presupuesto\u00bb admin_label=\u00bb101d get quote\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc9e00792-1360-4998-8cf9-5f6772c944ba\u00bb custom_padding=\u00bb6px|47px|6px|47px|false|false\u00bb global_module=\u00bb121848&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner admin_label=\u00bbFree Shipping Offer &#8211; UK and Ireland\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb hover_enabled=\u00bb0&#8243; global_module=\u00bb214421&#8243; global_colors_info=\u00bb{}\u00bb disabled_on=\u00bbon|on|on\u00bb disabled=\u00bbon\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_column_inner _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbPromo Text\u00bb module_id=\u00bbgeo-target-content\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb header_2_font=\u00bb|800|||||||\u00bb header_2_text_color=\u00bb#f48e00&#8243; header_2_font_size=\u00bb31px\u00bb header_3_font=\u00bb|600|||||||\u00bb header_3_font_size=\u00bb26px\u00bb header_3_line_height=\u00bb1.4em\u00bb link_option_url=\u00bbhttps:\/\/distributor.solinst.com\/free-shipping-uk-and-ireland?sc_cid=SUK-WC-content-banner-with-image\u00bb custom_css_main_element=\u00bbdisplay: none;\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><b><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-annoucement-1920x500-2.webp\" width=\"1920\" height=\"500\" alt=\"solinst uk ltd atiende a clientes de todo el reino unido e irlanda\" class=\"wp-image-212690 alignnone size-full\" srcset=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-annoucement-1920x500-2.webp 1920w, https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-annoucement-1920x500-2-1280x333.webp 1280w, https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-annoucement-1920x500-2-980x255.webp 980w, https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-annoucement-1920x500-2-480x125.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) and (max-width: 1280px) 1280px, (min-width: 1281px) 1920px, 100vw\" \/><\/b><\/h2>\n<h2 style=\"text-align: center;\"><b>\u00a1Grandes noticias para nuestros clientes del Reino Unido e Irlanda!<\/b><\/h2>\n<h3 style=\"text-align: center;\"><b>Env\u00edo gratuito en todos los pedidos realizados a Solinst UK Ltd<br \/>desde ahora hasta el 29 de mayo de 2026.  <\/b><\/h3>\n<h2 style=\"text-align: center;\"><b>OFERTA DE ENV\u00cdO GRATUITO  &gt;<\/b><\/h2>\n<p>[\/et_pb_text][et_pb_code admin_label=\u00bbC\u00f3digo Geo-Targeting\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb display_conditions=\u00bbW10=\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<script><!-- [et_pb_line_break_holder] -->document.addEventListener('DOMContentLoaded', function() {<!-- [et_pb_line_break_holder] -->    fetch('\/cdn-cgi\/trace')<!-- [et_pb_line_break_holder] -->        .then(response => response.text())<!-- [et_pb_line_break_holder] -->        .then(data => {<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->            const lines = data.split('\\n');<!-- [et_pb_line_break_holder] -->            const info = {};<!-- [et_pb_line_break_holder] -->            lines.forEach(line => {<!-- [et_pb_line_break_holder] -->                const [key, value] = line.split('=');<!-- [et_pb_line_break_holder] -->                if (key) info[key] = value;<!-- [et_pb_line_break_holder] -->            });<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->            \/\/ Check for location<!-- [et_pb_line_break_holder] -->      \t\t\tif (info.loc === 'IE' || info.loc === 'GB') {<!-- [et_pb_line_break_holder] -->    \t\t\t\t\tdocument.getElementById('geo-target-content').style.display = 'block';<!-- [et_pb_line_break_holder] -->\t\t\t\t\t\t}<!-- [et_pb_line_break_holder] -->        })<!-- [et_pb_line_break_holder] -->        .catch(error => console.error('Error fetching Cloudflare trace:', error));<!-- [et_pb_line_break_holder] -->});<!-- [et_pb_line_break_holder] --><\/script>[\/et_pb_code][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbMejore la eficiencia de su campo con el bombeo automatizado\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb46ad5c23-ecb8-466b-9973-452975f03683&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbresearch article\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb26px\u00bb header_2_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]Cuando se conecta a una <strong>bomba perist\u00e1ltica Solinst modelo 410 Mk5<\/strong>, el medidor de nivel de agua <strong>DrawDown<\/strong>101D se transforma en un sistema que gestiona autom\u00e1ticamente su proceso de muestreo.[\/et_pb_text][et_pb_heading title=\u00bbLa ventaja: control manos libres real\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb46ad5c23-ecb8-466b-9973-452975f03683&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text disabled_on=\u00bboff|off|off\u00bb admin_label=\u00bbresearch article\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb26px\u00bb header_2_font_size=\u00bb22px\u00bb custom_margin=\u00bb0px||20px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<strong>Control Autom\u00e1tico:<\/strong> El cable DrawDown Link permite al medidor de nivel de agua DrawDown 101D controlar autom\u00e1ticamente la bomba en funci\u00f3n del nivel de agua real del pozo.<\/p>\n<p><strong>Proteja su bomba:<\/strong> El sistema garantiza que la toma de la bomba permanezca sumergida de forma fiable durante la purga o el desarrollo del pozo, evitando el funcionamiento en seco y los da\u00f1os.<\/p>\n<p><strong>Agilice el muestreo de bajo caudal:<\/strong> Consiga caudales precisos y constantes mientras el medidor de nivel de agua DrawDown Meter 101D supervisa y controla la ca\u00edda de la altura hidr\u00e1ulica durante el muestreo de aguas subterr\u00e1neas de bajo caudal.<\/p>\n<p>El <strong>conjunto de cables DrawDown Link<\/strong> est\u00e1 disponible por separado para conectarlo a la <strong>bomba perist\u00e1ltica modelo 410 Mk5<\/strong>.[\/et_pb_text][et_pb_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/101d-water-level-drawdown-meter-connected-to-410-peristaltic-pump.webp\u00bb alt=\u00bbmedidor de descenso del nivel de agua solinst 101d conectado a la bomba perist\u00e1ltica 410&#8243; title_text=\u00bbMedidor de nivel de agua Solinst modelo 101D conectado a la bomba perist\u00e1ltica 410&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/101-water-level-meter\/get-quote.php?prod=101d\u00bb button_text=\u00bbObtener presupuesto\u00bb admin_label=\u00bb101d get quote\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbc9e00792-1360-4998-8cf9-5f6772c944ba\u00bb custom_padding=\u00bb6px|47px|6px|47px|false|false\u00bb global_module=\u00bb121848&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbAplicaciones ideales para el medidor de nivel de agua DrawDown\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb46ad5c23-ecb8-466b-9973-452975f03683&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][et_pb_text admin_label=\u00bbresearch article\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb26px\u00bb header_2_font_size=\u00bb22px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<ul>\n<li>Profundidad del agua en pozos, perforaciones, tuber\u00edas verticales y dep\u00f3sitos<\/li>\n<li>Control de la reducci\u00f3n durante:\n<ul>\n<li>Muestreo de aguas subterr\u00e1neas de bajo caudal<\/li>\n<li>Desarrollo y purga de pozos<\/li>\n<li>Aplicaciones de deshidrataci\u00f3n<\/li>\n<li>Pruebas de bombeo, slug, conductividad hidr\u00e1ulica, escal\u00f3n y otras pruebas de acu\u00edferos\/pozos<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbProductos relacionados\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb22px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#d3d3d3&#8243; global_module=\u00bb120904&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/101d-water-level-drawdown-meter-and-power-winder.webp\u00bb alt=\u00bb101d medidor de descenso del nivel de agua con bobinador instalado\u00bb title_text=\u00bb101D Medidor de nivel de agua con bobinador instalado\u00bb url=\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/101-power-winder\/101-power-winder.php\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#bcbcbc\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_margin=\u00bb60px||||false|false\u00bb custom_margin_tablet=\u00bb0px||||false|false\u00bb custom_margin_phone=\u00bb0px||||false|false\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>101 Bobinadora el\u00e9ctrica<\/strong><\/h2>\n<p>El <a href=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/101-power-winder\/101-power-winder.php\" title=\"101 Bobinadora el\u00e9ctrica\"><strong>101 Power Winder<\/strong><\/a> ofrece comodidad y facilidad de uso para todos los dispositivos Solinst montados en carretes. Es ligero y f\u00e1cil de acoplar a carretes Solinst de tama\u00f1o peque\u00f1o, mediano o grande, y es sencillo de ajustar para adaptarse a otros carretes del mercado. Enrolla sin esfuerzo longitudes de cinta m\u00e1s largas.  <\/p>\n<p>(La imagen muestra el 101 Power Winder instalado en el medidor de nivel de agua Solinst modelo 101D)<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/101-power-winder\/101-power-winder.php\u00bb button_text=\u00bbEnrolle sin esfuerzo cintas de mayor longitud\u00bb button_alignment=\u00bbright\u00bb button_alignment_tablet=\u00bbcenter\u00bb button_alignment_phone=\u00bbcenter\u00bb button_alignment_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb20px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_color=\u00bb#ff8500&#8243; button_border_radius=\u00bb20px\u00bb button_icon=\u00bb&#x3d;||divi||400&#8243; custom_padding=\u00bb0px|||||\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb16px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#d3d3d3&#8243; global_module=\u00bb120903&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/407-bladder-pumps.webp\u00bb alt=\u00bbbombas de vejiga solinst modelo 407&#8243; title_text=\u00bbBombas de vejiga Solinst modelo 407&#8243; url=\u00bbhttps:\/\/www.solinst.com\/products\/groundwater-samplers\/407-bladder-pumps\/index.php\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#bcbcbc\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_margin=\u00bb60px||||false|false\u00bb custom_margin_tablet=\u00bb0px||||false|false\u00bb custom_margin_phone=\u00bb0px||||false|false\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>Bombas de vejiga con cartuchos de vejiga f\u00e1ciles de sustituir<\/strong><\/h2>\n<p><a href=\"https:\/\/www.solinst.com\/products\/groundwater-samplers\/407-bladder-pumps\/index.php\" title=\"Bombas de vejiga Solinst\"><strong>Las bombas de vejiga Solinst<\/strong><\/a> cuentan ahora con cartuchos de vejiga Santoprene\u00ae que se sustituyen r\u00e1pida y f\u00e1cilmente sobre el terreno, sin necesidad de herramientas. Las bombas de vejiga de PVC son de bajo coste y excelentes para el muestreo de metales y en entornos duros y corrosivos. <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/www.solinst.com\/products\/groundwater-samplers\/407-bladder-pumps\/index.php\u00bb button_text=\u00bbMuestreo de aguas subterr\u00e1neas de bajo caudal\u00bb button_alignment=\u00bbright\u00bb button_alignment_tablet=\u00bbcenter\u00bb button_alignment_phone=\u00bbcenter\u00bb button_alignment_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb20px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_color=\u00bb#ff8500&#8243; button_border_radius=\u00bb20px\u00bb button_icon=\u00bb&#x3d;||divi||400&#8243; custom_padding=\u00bb0px|||||\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb16px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00bb custom_margin=\u00bb50px||3em||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner saved_specialty_column_type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbEntradas de blog relacionadas\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|700|||||||\u00bb title_font_size=\u00bb22px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00bb1_2,1_2&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_width_bottom=\u00bb1px\u00bb border_color_bottom=\u00bb#d3d3d3&#8243; global_module=\u00bb120907&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/09\/importance-of-measuring-water-level-drawdown.webp\u00bb alt=\u00bbimportancia de medir el descenso del nivel del agua\u00bb title_text=\u00bbImportancia de medir el descenso del nivel del agua\u00bb url=\u00bbhttps:\/\/www.solinst.com\/onthelevel-news\/water-level-monitoring\/the-importance-of-measuring-drawdown\/\u00bb align=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb border_color_all=\u00bb#bcbcbc\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00bb1_2&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_2_line_height=\u00bb1.3em\u00bb custom_margin=\u00bb60px||||false|false\u00bb custom_margin_tablet=\u00bb0px||||false|false\u00bb custom_margin_phone=\u00bb0px||||false|false\u00bb custom_margin_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h2><strong>La importancia de medir el descenso del nivel del agua<\/strong><\/h2>\n<p>C\u00f3mo el uso conjunto de un <strong>Levelogger<\/strong> y <strong>un medidor de<\/strong> descenso del <strong>nivel del agua 101D<\/strong> proporciona datos esenciales.<br \/>\u00bfQu\u00e9 es el descenso del nivel del agua? El descenso del nivel es un cambio en el nivel de las aguas subterr\u00e1neas debido a un estr\u00e9s aplicado, causado por eventos como: Bombeo de un pozo Bombeo de un pozo vecino Extracci\u00f3n intensiva de agua del \u00e1rea local Descensos estacionales al disminuir las tasas de recarga&#8230;. <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/101d-water-level-drawdown-meter\/101d.php\u00bb button_text=\u00bb\u00bfC\u00f3mo se mide la reducci\u00f3n?\u00bb button_alignment=\u00bbright\u00bb button_alignment_tablet=\u00bbcenter\u00bb button_alignment_phone=\u00bbcenter\u00bb button_alignment_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb20px\u00bb button_text_color=\u00bb#000000&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_color=\u00bb#ff8500&#8243; button_border_radius=\u00bb20px\u00bb button_icon=\u00bb&#x3d;||divi||400&#8243; custom_padding=\u00bb0px|||||\u00bb button_text_size_tablet=\u00bb18px\u00bb button_text_size_phone=\u00bb16px\u00bb button_text_size_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbAdobe Analytics Code\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code admin_label=\u00bbC\u00f3digo AA para esta p\u00e1gina\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<!-- SiteCatalyst code version: H.21. Copyright 1996-2010 Adobe, Inc. All Rights Reserved More info available at http:\/\/www.omniture.com --><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\" src=\"\/\/www.solinst.com\/s_code.js\"><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->s.pageName=\"101d home\"<!-- [et_pb_line_break_holder] -->s.server=\"\"<!-- [et_pb_line_break_holder] -->s.channel=\"products\"<!-- [et_pb_line_break_holder] -->s.pageType=\"\"<!-- [et_pb_line_break_holder] -->s.prop1=\"level measurement devices\"<!-- [et_pb_line_break_holder] -->s.prop2=\"101d water level drawdown meter\"<!-- [et_pb_line_break_holder] -->s.prop3=\"101d home\"<!-- [et_pb_line_break_holder] -->s.prop4=\"\"<!-- [et_pb_line_break_holder] -->s.prop5=\"\"<!-- [et_pb_line_break_holder] -->s.prop6=\"\"<!-- [et_pb_line_break_holder] -->s.prop7=\"\"<!-- [et_pb_line_break_holder] -->s.prop8=\"\"<!-- [et_pb_line_break_holder] -->s.prop9=\"\"<!-- [et_pb_line_break_holder] -->s.prop10=\"\"<!-- [et_pb_line_break_holder] -->s.prop11=\"\"<!-- [et_pb_line_break_holder] -->s.prop12=\"\"<!-- [et_pb_line_break_holder] -->s.prop13=\"\"<!-- [et_pb_line_break_holder] -->s.prop14=\"\"<!-- [et_pb_line_break_holder] -->s.prop15=\"\"<!-- [et_pb_line_break_holder] -->s.prop16=\"\"<!-- [et_pb_line_break_holder] -->s.prop17=\"\"<!-- [et_pb_line_break_holder] -->s.prop18=\"\"<!-- [et_pb_line_break_holder] -->s.prop19=\"\"<!-- [et_pb_line_break_holder] -->s.prop20=\"\"<!-- [et_pb_line_break_holder] -->s.prop21=\"\"<!-- [et_pb_line_break_holder] -->s.prop22=\"\"<!-- [et_pb_line_break_holder] -->s.prop23=\"\"<!-- [et_pb_line_break_holder] -->s.prop24=\"\"<!-- [et_pb_line_break_holder] -->s.prop25=\"\"<!-- [et_pb_line_break_holder] -->s.prop26=\"\"<!-- [et_pb_line_break_holder] -->s.prop27=\"\"<!-- [et_pb_line_break_holder] -->s.prop28=\"\"<!-- [et_pb_line_break_holder] -->s.prop29=\"\"<!-- [et_pb_line_break_holder] -->s.prop30=\"\"<!-- [et_pb_line_break_holder] -->s.prop31=\"\"<!-- [et_pb_line_break_holder] -->s.prop32=\"\"<!-- [et_pb_line_break_holder] -->s.prop33=\"\"<!-- [et_pb_line_break_holder] -->s.hier1=\"solinst:products:level measurement devices:101d water level drawdown meter:101d home\"<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/* Conversion Variables *\/<!-- [et_pb_line_break_holder] -->s.campaign=\"\"<!-- [et_pb_line_break_holder] -->s.events=\"\"<!-- [et_pb_line_break_holder] -->s.eVar1=\"\"<!-- [et_pb_line_break_holder] -->s.eVar2=\"\"<!-- [et_pb_line_break_holder] -->s.eVar3=\"\"<!-- [et_pb_line_break_holder] -->s.eVar4=\"\"<!-- [et_pb_line_break_holder] -->s.eVar5=\"\"<!-- [et_pb_line_break_holder] -->s.eVar6=\"\"<!-- [et_pb_line_break_holder] -->s.eVar7=\"\"<!-- [et_pb_line_break_holder] -->s.eVar8=\"\"<!-- [et_pb_line_break_holder] -->s.eVar9=\"\"<!-- [et_pb_line_break_holder] -->s.eVar10=\"\"<!-- [et_pb_line_break_holder] -->s.eVar11=\"\"<!-- [et_pb_line_break_holder] -->s.eVar12=\"\"<!-- [et_pb_line_break_holder] -->s.eVar13=\"\"<!-- [et_pb_line_break_holder] -->s.eVar14=\"\"<!-- [et_pb_line_break_holder] -->s.eVar15=\"\"<!-- [et_pb_line_break_holder] -->s.eVar16=\"\"<!-- [et_pb_line_break_holder] -->s.eVar17=\"\"<!-- [et_pb_line_break_holder] -->s.state=\"\"<!-- [et_pb_line_break_holder] -->s.zip=\"\"<!-- [et_pb_line_break_holder] -->\/************* DO NOT ALTER ANYTHING BELOW THIS LINE ! **************\/<!-- [et_pb_line_break_holder] -->var s_code=s.t();if(s_code)document.write(s_code)\/\/--><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->if(navigator.appVersion.indexOf('MSIE')>=0)document.write(unescape('%3C')+'!-'+'-')<!-- [et_pb_line_break_holder] -->\/\/--><\/script><!-- [et_pb_line_break_holder] --><noscript><!-- [et_pb_line_break_holder] -->  <a href=\"https:\/\/www.omniture.com\" title=\"Anal\u00edtica web\"><!-- [et_pb_line_break_holder] -->    <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solinst.d2.sc.omtrdc.net\/b\/ss\/solinst-prod\/1\/H.21--NS\/0\" height=\"1\" width=\"1\" border=\"0\" alt=\"\"><!-- [et_pb_line_break_holder] -->  <\/a><!-- [et_pb_line_break_holder] --><\/noscript><!-- [et_pb_line_break_holder] --><!--\/DO NOT REMOVE\/--><!-- [et_pb_line_break_holder] --><!-- End SiteCatalyst code version: H.21. -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"https:\/\/www.solinst.com\/es\/\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"et-pb-icon dsm_home_icon\">\ue009<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\tHome\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">5<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div> &nbsp; Datos precisos sobre el nivel del agua Instrumentos fiables y duraderos&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Deje de cuidar su bomba perist\u00e1ltica. El medidor de descenso del nivel de agua Solinst 101D automatiza sus pruebas de muestreo y descenso del nivel de agua para ahorrar tiempo y garantizar resultados precisos. Modos de nivel de agua est\u00e1tico y descenso en un metro Una c\u00f3moda palanca facilita el cambio entre las dos funciones Longitudes de cinta de hasta 1500 m (5000 pies) El medidor de descenso del nivel de agua modelo 101D es la herramienta esencial de doble funci\u00f3n en la que conf\u00edan los profesionales de campo, ahora con capacidad de automatizaci\u00f3n mejorada. Utilice el sencillo conmutador para alternar entre mediciones est\u00e1ticas del nivel de agua en pozos, sondeos y dep\u00f3sitos, y la monitorizaci\u00f3n de la reducci\u00f3n del nivel para pruebas de acu\u00edferos y pozos. Adem\u00e1s de su robusto dise\u00f1o y su precisa cinta plana marcada con l\u00e1ser, el medidor de nivel de agua 101D ofrece una nueva y potente funci\u00f3n que redefine la eficiencia sobre el terreno.Medidor de descenso del nivel de agua 2 productos en 1 Modos de nivel de agua est\u00e1tico y descenso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":140799,"parent":12176,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"folder":[117],"class_list":["post-121591","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>101D Medidor de descenso del nivel de agua<\/title>\n<meta name=\"description\" content=\"Medidor de descenso del nivel de agua 101D ideal para el control del descenso del nivel de agua durante la deshidrataci\u00f3n, el muestreo de aguas subterr\u00e1neas de bajo caudal, las pruebas de bombeo y mucho m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"101D Medidor de descenso del nivel de agua\" \/>\n<meta property=\"og:description\" content=\"Descubra las ventajas de utilizar un medidor de descenso del nivel de agua para controlar y gestionar eficazmente el nivel de agua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/\" \/>\n<meta property=\"og:site_name\" content=\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-01T16:55:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/12\/featureimages-lmd-101d.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Descubra las ventajas de utilizar un medidor de descenso del nivel de agua para controlar y gestionar eficazmente el nivel de agua.\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/\",\"name\":\"101D Medidor de descenso del nivel de agua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/featureimages-lmd-101d.webp\",\"datePublished\":\"2025-09-04T19:37:45+00:00\",\"dateModified\":\"2026-06-01T16:55:57+00:00\",\"description\":\"Medidor de descenso del nivel de agua 101D ideal para el control del descenso del nivel de agua durante la deshidrataci\u00f3n, el muestreo de aguas subterr\u00e1neas de bajo caudal, las pruebas de bombeo y mucho m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/featureimages-lmd-101d.webp\",\"contentUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/featureimages-lmd-101d.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/101d-medidor-de-descenso-del-nivel-de-agua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dispositivos de medici\u00f3n de nivel\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/productos\\\/dispositivos-de-medicion-de-nivel\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"101D Medidor de descenso del nivel de agua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/\",\"name\":\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\",\"description\":\"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solinst.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"101D Medidor de descenso del nivel de agua","description":"Medidor de descenso del nivel de agua 101D ideal para el control del descenso del nivel de agua durante la deshidrataci\u00f3n, el muestreo de aguas subterr\u00e1neas de bajo caudal, las pruebas de bombeo y mucho m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/","og_locale":"es_ES","og_type":"article","og_title":"101D Medidor de descenso del nivel de agua","og_description":"Descubra las ventajas de utilizar un medidor de descenso del nivel de agua para controlar y gestionar eficazmente el nivel de agua.","og_url":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/","og_site_name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","article_modified_time":"2026-06-01T16:55:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/12\/featureimages-lmd-101d.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_description":"Descubra las ventajas de utilizar un medidor de descenso del nivel de agua para controlar y gestionar eficazmente el nivel de agua.","twitter_misc":{"Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/","url":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/","name":"101D Medidor de descenso del nivel de agua","isPartOf":{"@id":"https:\/\/www.solinst.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/#primaryimage"},"image":{"@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/12\/featureimages-lmd-101d.webp","datePublished":"2025-09-04T19:37:45+00:00","dateModified":"2026-06-01T16:55:57+00:00","description":"Medidor de descenso del nivel de agua 101D ideal para el control del descenso del nivel de agua durante la deshidrataci\u00f3n, el muestreo de aguas subterr\u00e1neas de bajo caudal, las pruebas de bombeo y mucho m\u00e1s.","breadcrumb":{"@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/#primaryimage","url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/12\/featureimages-lmd-101d.webp","contentUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/12\/featureimages-lmd-101d.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/101d-medidor-de-descenso-del-nivel-de-agua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.solinst.com\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/www.solinst.com\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Dispositivos de medici\u00f3n de nivel","item":"https:\/\/www.solinst.com\/es\/productos\/dispositivos-de-medicion-de-nivel\/"},{"@type":"ListItem","position":4,"name":"101D Medidor de descenso del nivel de agua"}]},{"@type":"WebSite","@id":"https:\/\/www.solinst.com\/es\/#website","url":"https:\/\/www.solinst.com\/es\/","name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","description":"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solinst.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/pages\/121591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/comments?post=121591"}],"version-history":[{"count":47,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/pages\/121591\/revisions"}],"predecessor-version":[{"id":229482,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/pages\/121591\/revisions\/229482"}],"up":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/pages\/12176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/media\/140799"}],"wp:attachment":[{"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/media?parent=121591"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.solinst.com\/es\/wp-json\/wp\/v2\/folder?post=121591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}