{"id":67027,"date":"2025-03-06T13:57:56","date_gmt":"2025-03-06T13:57:56","guid":{"rendered":"https:\/\/www.solinst.com\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/"},"modified":"2026-05-28T18:57:42","modified_gmt":"2026-05-28T18:57:42","slug":"capteurs-dazurants-optiques","status":"publish","type":"page","link":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/","title":{"rendered":"Capteurs d&rsquo;azurants optiques"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; fullwidth=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_fullwidth_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-easy-probe-water-quality-sonde-1920&#215;500-1.webp\u00a0\u00bb alt=\u00a0\u00bbsondes de qualit\u00e9 de l&#039;eau solinst eureka easyprobe\u00a0\u00bb title_text=\u00a0\u00bbSondes de qualit\u00e9 de l&#039;eau Solinst Eureka EasyProbe\u00a0\u00bb src_tablet=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-easy-probe-water-quality-sonde-965&#215;500-1.webp\u00a0\u00bb src_phone=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-easy-probe-water-quality-sonde-965&#215;500-1.webp\u00a0\u00bb src_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbH1 and breadcrumbs\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bb792ca5bd-0808-46bd-9ce7-3bcb8e74f4d3&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bb4b28f470-0d73-4e9d-b92d-e6f41f2cea24&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbCapteurs \u00e0 azurant optique : Surveillance de la qualit\u00e9 de l&#039;eau\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bb6983e4e7-a6e0-4a8d-b486-49939fd240c0&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][dsm_breadcrumbs disabled_on=\u00a0\u00bbon|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb home_icon_text_color=\u00a0\u00bb#d6d6d6&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/dsm_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbMobile-Only Nav with Offset\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb4759a92f-4b27-4854-bb2c-299854634e93&Prime; sticky_offset_top=\u00a0\u00bb127px\u00a0\u00bb global_module=\u00a0\u00bb45704&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb90%\u00a0\u00bb custom_margin=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code admin_label=\u00a0\u00bbEureka Mobile Nav &#8211; S\u00e9lectionner un menu d\u00e9roulant\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_free_form=\u00a0\u00bbselect {||||      font-size: 1em; \/* Adjust font size *\/||      padding: 10px;   \/* Optional: Increase padding for better spacing *\/||      width: 100%;||      box-sizing: border-box;\/* Optional: Adjust width to fit the container *\/||      height: 50px;||}||||    \/* Style for dropdown options (fallback if needed) *\/||select option {||      font-size: 1.2em; \/* Ensures option text matches select styling *\/||      width: 100%;||    }\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<select name=\"dropdown\" onchange=\"location = this.value;\"><!-- [et_pb_line_break_holder] --><option value=\"\">Solinst Eureka Menu<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/\">Page principale de Solinst Eureka<\/option><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/\">Sondes de qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/\">-Sondes multiparam\u00e8tres Manta<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-20-multiparameter-probes\/\">&#8211;Manta Plus 20<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-25-multiparameter-probes\/\">&#8211;Manta Plus 25<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-30-multiparameter-probe\/\">&#8211;Manta Plus 30<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-35-multiparameter-probes\/\">&#8211;Manta Plus 35<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-f35-multiparameter-water-quality-probes\/\">&#8211;Manta F35<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-40-multiparameter-probe\/\">&#8211;Manta Plus 40<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/instructions\/\">&#8211;Instructions pour les sondes de qualit\u00e9 de l&rsquo;eau de la s\u00e9rie Manta<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/instructions\/water-quality-probes-quick-reference\/\">&#8212;R\u00e9f\u00e9rence rapide pour les sondes de qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/\">-Trim\u00e8tre<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/datasheet\/\">&#8211;Fiche de donn\u00e9es<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/5001-trimeter-sonde-quote-form\/\">&#8211;Obtenir un devis<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/\">-Sonde de qualit\u00e9 de l&rsquo;eau EasyProbe<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/datasheet\/\">&#8211;Fiche de donn\u00e9es<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/5001-easyprobe-sondes-quote-form\/\">&#8211;Obtenir un devis<\/option><!-- [et_pb_line_break_holder] -->        <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/\">Capteurs de qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/temperature-sensor\/\">-Capteur de temp\u00e9rature<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ph-sensors\/\">-Capteurs de pH<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/orp-oxidation-reduction-potential-sensors\/\">-Capteur ORP<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/turbidity-sensors\/\">-Capteurs de turbidit\u00e9<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/dissolved-oxygen-sensors\/\">-Capteurs d&rsquo;oxyg\u00e8ne dissous<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/conductivity-sensors\/\">-Capteurs de conductivit\u00e9<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/transmittance-sensors\/\">-Capteurs de transmittance<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/pressure-sensors\/\">-Capteurs de pression<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/total-dissolved-gas-sensors\/\">-Capteurs de gaz dissous totaux<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/c02-carbon-dioxide-sensors\/\">Capteurs de dioxyde de carbone -CO2<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/par-photosynthetically-active-radiation-sensors\/\">Capteurs de rayonnement actif de la photosynth\u00e8se -PAR<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/fluorometers\/\">-fluorom\u00e8tres<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/chlorophyll-sensors\/\">&#8211;Capteurs de chlorophylle<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/blue-green-algae-sensors\/\">&#8211;Capteurs d&rsquo;algues bleues<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/cdom-colored-dissolved-organic-matter-sensors\/\">Capteurs color\u00e9s de mati\u00e8re organique dissoute &#8211;CDOM<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/optical-brightener-sensors\/\">&#8211;Capteurs optiques d&rsquo;\u00e9claircissement<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/tryptophan-sensors\/\">&#8211;Capteurs de tryptophane<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/rhodamine-sensors\/\">&#8211;Capteurs \u00e0 rhodamine<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/flourescein-sensors\/\">&#8211;Capteurs \u00e0 fluoresc\u00e9ine<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ptsa-fluorescence-sensors\/\">&#8211;Capteurs de fluorescence PTSA<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/refined-oil-and-fuel-sensors\/\">&#8211;Capteurs d&rsquo;huile et de carburant d\u00e9finis<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/crude-oil-sensors\/\">&#8211;Capteurs de p\u00e9trole brut<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ise-ion-selective-electrodes\/\">\u00c9lectrodes s\u00e9lectives d&rsquo;ions -ISE<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/water-quality-sensor-configurations\/\">-Configurations des capteurs de qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/\">Appareils de terrain et applications robustes<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-mobile-wireless-data-device\/\">-MantaMobile<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-mobile-wireless-data-device\/datasheet\/\">&#8211;Fiche de donn\u00e9es<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-link-app\/\">-MantaLink<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/\">-Comprim\u00e9s rod\u00e9s<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/samsung-galaxy-tab-active3\/\">&#8211;Samsung Galaxy Tab Active3<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/juniper-systems-mesa3\/\">&#8211;Juniper Systems MESA3<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/ipad-mini-ruggedized-tablet\/\">&#8211;iPad Mini Tablette durcie<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/juniper-cedar-ct8x2\/\">&#8211;Table robuste CT8X2 en c\u00e8dre de Juniper<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/remote-water-quality-monitoring\/\">-Surveillance \u00e0 distance de la qualit\u00e9 de l&rsquo;eau  <\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-monitoring-accessories\/\">Accessoires pour la surveillance de la qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-monitoring-applications\/\">Applications de surveillance de la qualit\u00e9 de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] -->   <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/quote\/\">Obtenir un devis<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/contact\/\">Contactez nous<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/distributors\/\">Solinst Eureka Distributeurs<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/support\/\">Solinst Eureka Support<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/support\/rma-return-material-authorization-form\/\">-Autorisation de retour de mat\u00e9riel<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/maintenance-program\/\">Programme d&rsquo;entretien Solinst Eureka<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/\">Cas de r\u00e9ussite Solinst Eureka<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/manta-probes-monitor-water-quality-at-jellyfish-lake-palau\/\">-Sondes Manta utilis\u00e9es au lac JellyFish<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/ut-dallas-disaster-team-uses-eureka-probes-in-dangerous-environments\/\">-Sondes Eureka utilis\u00e9es dans des environnements dangereux<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/solar-charged-continous-monitoring-in-rugged-conditions\/\">-SFPUC : Surveillance continue sur charge solaire dans des conditions difficiles<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/scientists-monitor-water-in-everglades-with-hydrostation\/\">-Des scientifiques surveillent l&rsquo;eau dans les Everglades gr\u00e2ce \u00e0 une station d&rsquo;\u00e9puration en mallette<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/maintaining-water-quality-in-a-formerly-flammable-river\/\">-Maintien de la qualit\u00e9 de l&rsquo;eau dans une rivi\u00e8re anciennement inflammable<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/after-a-megafire-how-are-waterways-impacted-by-a-wildfire\/\">-BYU : Apr\u00e8s un grand incendie, quel est l&rsquo;impact sur les cours d&rsquo;eau d&rsquo;un incendie de for\u00eat ?<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/robots-used-to-analyze-aquatic-environments\/\">-UT : Robots utilis\u00e9s pour analyser les environnements aquatiques<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/nps-eastern-river-and-mountains-network\/\">-NPS, R\u00e9seau des rivi\u00e8res et des montagnes de l&rsquo;Est<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/remote-monitoring-for-early-warning-of-water-pollution-events\/\">-Surveillance \u00e0 distance pour l&rsquo;alerte pr\u00e9coce en cas de pollution de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/turbidity-monitoring-establishes-baseline-data-prior-to-construction-activities\/\">-La surveillance de la turbidit\u00e9 a permis d&rsquo;\u00e9tablir des donn\u00e9es de r\u00e9f\u00e9rence avant les activit\u00e9s de construction.<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/monitoring-in-high-hypolimnetic-sulfide-concentrations\/\">-Le profileur vertical permet une surveillance continue des concentrations \u00e9lev\u00e9es de sulfure en milieu hypolimnique.<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/water-quality-monitoring-in-extreme-bio-fouling-conditions\/\">-Contr\u00f4le continu de la qualit\u00e9 de l&rsquo;eau dans des conditions extr\u00eames de bio-encrassement<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/high-resolution-temporal-monitoring-of-an-arid-urban-lake\/\">-Surveillance temporelle \u00e0 haute r\u00e9solution d&rsquo;un lac urbain aride<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/water-reuse-model-research\/\">-Recherche sur le mod\u00e8le de r\u00e9utilisation de l&rsquo;eau<\/option><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/select>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; specialty=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bb5a5bca26-a9a5-4e6c-8fca-d64da3bdcd40&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_menu menu_id=\u00a0\u00bb252&Prime; admin_label=\u00a0\u00bbEureka Main Nav\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb242faa89-ac4f-4e46-90fe-505e8c1eab79&Prime; global_module=\u00a0\u00bb45700&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_menu][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb10px||||false|false\u00a0\u00bb global_module=\u00a0\u00bb46733&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p><a href=\"https:\/\/solinst.com\/eureka\" title=\"Solinst Eureka\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-logo-800w.webp\" width=\"271\" height=\"49\" alt=\"solinst eureka logo\" class=\"wp-image-44307 alignnone size-full\" \/><\/strong><\/a><\/p>\n<p><strong>Solinst Eureka<\/strong><br \/>2113 Wells Branch Pkwy, Suite 4400<br \/>Austin, TX, USA<br \/>78728<\/p>\n<p>Tel: +1 512-302-4333<br \/>Fax: +1 512-251-6842<br \/>email: <a href=\"mailto:eureka@solinst.com\">eureka@solinst.com<\/a><\/p>\n<p>[\/et_pb_text][et_pb_slider disabled_on=\u00a0\u00bbon|on|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb display_conditions=\u00a0\u00bbW10=\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.solinst.com\/instruments\/dataloggers-and-telemetry-systems\/3001-levelogger\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position1&#038;utm_campaign=3001&Prime; global_module=\u00a0\u00bb53188&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slide button_text=\u00a0\u00bbLevelogger\u00a0\u00bb button_link=\u00a0\u00bbhttps:\/\/www.solinst.com\/fr\/produits\/enregistreurs-de-donnees-et-systemes-de-telemetrie\/3001-detecteur-de-niveau\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position1&amp;utm_campaign=3001&Prime; use_bg_overlay=\u00a0\u00bbon\u00a0\u00bb bg_overlay_color=\u00a0\u00bbrgba(224,97,0,0.58)\u00a0\u00bb button_text_tablet=\u00a0\u00bb\u00a0\u00bb button_text_phone=\u00a0\u00bb\u00a0\u00bb button_text_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb content_tablet=\u00a0\u00bb\u00a0\u00bb content_phone=\u00a0\u00bb\u00a0\u00bb content_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bb#F07C00&Prime; background_enable_color=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-absolute-water-level-datalogging.webp\u00a0\u00bb background_enable_image=\u00a0\u00bbon\u00a0\u00bb background_position=\u00a0\u00bbtop_center\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58025&Prime; button_border_width=\u00a0\u00bb2px\u00a0\u00bb button_border_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bb|600|||||||\u00a0\u00bb background_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb button_border_width__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb button_border_width__hover=\u00a0\u00bb2px\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb]<\/p>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h2>Donn\u00e9es pr\u00e9cises sur le niveau de l&rsquo;eau<\/h2>\n<p><b>Des instruments fiables qui durent<\/b><\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][et_pb_slider disabled_on=\u00a0\u00bbon|on|on\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.solinst.com\/careers\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position2&#038;utm_campaign=SUK-regional-sales-manager\u00a0\u00bb disabled=\u00a0\u00bbon\u00a0\u00bb global_module=\u00a0\u00bb53561&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_slide heading=\u00a0\u00bbSolinst UK recrute !\u00a0\u00bb button_text=\u00a0\u00bbDirecteur r\u00e9gional des ventes\u00a0\u00bb button_link=\u00a0\u00bbhttps:\/\/www.solinst.com\/careers\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position2&amp;utm_campaign=SUK-regional-sales-manager\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_color=\u00a0\u00bb#000000&Prime; header_font_size=\u00a0\u00bb38px\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb background_enable_color=\u00a0\u00bbon\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-ltd.webp\u00a0\u00bb background_enable_image=\u00a0\u00bbon\u00a0\u00bb background_size=\u00a0\u00bbcontain\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_bg_color=\u00a0\u00bb#f58025&Prime; button_border_width=\u00a0\u00bb2px\u00a0\u00bb button_border_color=\u00a0\u00bb#ffffff\u00a0\u00bb button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_font=\u00a0\u00bb|600|||||||\u00a0\u00bb button_custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb button_custom_padding=\u00a0\u00bb1px||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb76px||||false|false\u00a0\u00bb header_text_shadow_style=\u00a0\u00bbpreset5&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_transition=\u00a0\u00bbon\u00a0\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][et_pb_column type=\u00a0\u00bb3_4&Prime; specialty_columns=\u00a0\u00bb3&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bb3d476e59-90e6-46d3-a8fc-802e4e9a9788&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY2ODk3In19@\u00a0\u00bb button_text=\u00a0\u00bbCapteurs de mati\u00e8re organique dissoute color\u00e9e CDOM\u00a0\u00bb admin_label=\u00a0\u00bbNext Button\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bb2874de2c-0fb9-4b79-a995-edb56fb31e3b\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY3MDUwIn19@\u00a0\u00bb button_text=\u00a0\u00bbCapteurs de tryptophane\u00a0\u00bb admin_label=\u00a0\u00bbNext Button\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bb9559c3e8-ec08-4752-8f0c-e89abbf14bdf\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb3d68e16c-1ed2-447f-b17f-a63c20af3cf6&Prime; locked=\u00a0\u00bboff\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dsm_icon_list icon_font_size=\u00a0\u00bb30px\u00a0\u00bb list_alignment=\u00a0\u00bbflex-end\u00a0\u00bb text_indent=\u00a0\u00bb10px\u00a0\u00bb list_alignment_tablet=\u00a0\u00bbflex-end\u00a0\u00bb list_alignment_phone=\u00a0\u00bbflex-start\u00a0\u00bb list_alignment_last_edited=\u00a0\u00bbon|desktop\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb text_font=\u00a0\u00bb|600|||||||\u00a0\u00bb link_option_url_new_window=\u00a0\u00bbon\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][dsm_icon_list_child text=\u00a0\u00bb5001 Fluorom\u00e8tres PDF\u00a0\u00bb font_icon=\u00a0\u00bb&#xf1c1;||fa||900&Prime; icon_color=\u00a0\u00bb#ff8500&Prime; url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/data\/5001-fluorometers.pdf\u00a0\u00bb url_new_window=\u00a0\u00bbon\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb icon_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb icon_color__hover=\u00a0\u00bb#828282&Prime; text_text_color__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb text_text_color__hover=\u00a0\u00bb#7a7a7a\u00a0\u00bb][\/dsm_icon_list_child][\/dsm_icon_list][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb3676f7e6-7b83-4698-94ce-2cc9fa9ae43d\u00a0\u00bb custom_padding=\u00a0\u00bb0px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_padding=\u00a0\u00bb|||0px|false|false\u00a0\u00bb custom_css_free_form=\u00a0\u00bbwidth: 68%!important;||margin-right: 2%!important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb background__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb background_color__hover=\u00a0\u00bb\u00a0\u00bb background_enable_color__hover=\u00a0\u00bboff\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_font_size=\u00a0\u00bb24px\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong>Pourquoi voudrais-je mesurer les azurants optiques ?<\/strong><\/h2>\n<p>Les azurants optiques (OBA) ou les agents de blanchiment fluorescents (FWA) sont ajout\u00e9s \u00e0 des produits tels que les savons de lessive, les d\u00e9tergents ou les agents de nettoyage. Les tissus ou les mat\u00e9riaux absorbent les OBA au cours du processus de lavage ou de nettoyage. Lorsqu&rsquo;ils sont \u00e9clair\u00e9s par une lumi\u00e8re ultraviolette, ils deviennent fluorescents et font para\u00eetre les produits et les tissus plus brillants.  <\/p>\n<p>Les eaux us\u00e9es des blanchisseries sont le plus gros contributeur d&rsquo;azurants dans les syst\u00e8mes d&rsquo;assainissement. Les contributions FWA ou OBA au volume total de la plupart des d\u00e9tergents de blanchisserie sont inf\u00e9rieures \u00e0 0,5 %, mais une grande partie (5-80 %) peut rester dans les eaux us\u00e9es rejet\u00e9es sous forme de compos\u00e9s dissous (mol\u00e9culaires). La pr\u00e9sence d&rsquo;azurants dans les syst\u00e8mes d&rsquo;eau dans lesquels les eaux us\u00e9es sont d\u00e9vers\u00e9es peut signifier que les syst\u00e8mes septiques sont d\u00e9faillants, qu&rsquo;il y a des fuites d&rsquo;eaux us\u00e9es ou qu&rsquo;il n&rsquo;y a pas de traitement de l&rsquo;eau. Par cons\u00e9quent, la d\u00e9tection d&rsquo;azurants optiques dans les syst\u00e8mes aquatiques peut aider les municipalit\u00e9s ou les chercheurs \u00e0 corriger les d\u00e9faillances des syst\u00e8mes et \u00e0 \u00e9viter une augmentation de l&rsquo;apport anthropique susceptible d&rsquo;avoir un impact consid\u00e9rable sur les \u00e9cosyst\u00e8mes.   <\/p>\n<p>Des \u00e9tudes ont montr\u00e9 une corr\u00e9lation entre la fluorescence des azurants et les niveaux de coliformes f\u00e9caux dans les environnements aquatiques. La qualit\u00e9 de l&rsquo;eau est actuellement \u00e9valu\u00e9e en fonction des normes relatives aux coliformes f\u00e9caux par les agences f\u00e9d\u00e9rales, \u00e9tatiques et municipales. L&rsquo;acc\u00e8s du public aux plans d&rsquo;eau tels que les lacs, les rivi\u00e8res ou les plages qui ne r\u00e9pondent pas \u00e0 ces normes peut \u00eatre restreint, ce qui a un impact sur le tourisme et, en fin de compte, sur l&rsquo;\u00e9conomie locale. Le principal probl\u00e8me dans la pr\u00e9vention de l&rsquo;augmentation des niveaux de coliformes f\u00e9caux est l&rsquo;incapacit\u00e9 \u00e0 d\u00e9terminer la source de la contamination (humaine\/non humaine). Les eaux us\u00e9es des blanchisseries sont g\u00e9n\u00e9ralement \u00e9vacu\u00e9es par les \u00e9gouts domestiques ou les fosses septiques ; les azurants font donc partie des eaux us\u00e9es. La corr\u00e9lation entre les azurants et les niveaux de coliformes f\u00e9caux peut fournir des informations pr\u00e9cieuses pour aider les chercheurs \u00e0 d\u00e9terminer si les sources de contamination sont attribu\u00e9es aux d\u00e9chets humains.     <\/p>\n<p>Les azurants sont tr\u00e8s sensibles \u00e0 l&rsquo;adsorption. Ils sont \u00e9limin\u00e9s des eaux de surface et des eaux souterraines par adsorption sur le sol et les mati\u00e8res organiques. Cela permet aux chercheurs d&rsquo;\u00e9valuer l&rsquo;efficacit\u00e9 de l&rsquo;\u00e9puration naturelle des eaux us\u00e9es en d\u00e9terminant les concentrations d&rsquo;azurants dans les eaux souterraines ou de surface.  <\/p>\n<h2><strong>Comment les azurants optiques sont-ils mesur\u00e9s ?<\/strong><\/h2>\n<p><span>Les azurants optiques, ou agents de blanchiment fluorescents (FWA dans l&rsquo;industrie des d\u00e9tergents), sont des compos\u00e9s qui sont excit\u00e9s (activ\u00e9s) par des longueurs d&rsquo;onde de lumi\u00e8re dans le proche ultraviolet (UV) (360 \u00e0 365 nm), et qui \u00e9mettent ensuite de la lumi\u00e8re dans le bleu (400 \u00e0 440 nm). Les \u00e9lectrons des mol\u00e9cules fluorescentes sont excit\u00e9s dans un \u00e9tat d&rsquo;\u00e9nergie plus \u00e9lev\u00e9 par l&rsquo;absorption de la lumi\u00e8re et \u00e9mettent ensuite une petite quantit\u00e9 de chaleur et de fluorescence lorsque les \u00e9lectrons retournent \u00e0 leur \u00e9tat fondamental. La fluorescence du second \u00e9tat excit\u00e9 est mesur\u00e9e par le fluorom\u00e8tre OBA d&rsquo;Eureka et convertie en ppb d&rsquo;OBA jusqu&rsquo;\u00e0 2500 ppb.  <\/span><\/p>\n<h2><strong>Que dois-je savoir sur la mesure des azurants optiques sur le terrain ?<\/strong><\/h2>\n<p><span>Le capteur d&rsquo;azurant optique de Solinst Eureka poss\u00e8de une large plage dynamique (&gt;5000 parties par million) qui lui permet de fonctionner dans la plupart des environnements aquatiques, et sa haute r\u00e9solution augmente sa pr\u00e9cision. Le MantaPlus avec capteur \u00e0 azurant optique peut \u00eatre utilis\u00e9 dans le cadre d&rsquo;\u00e9tudes visant \u00e0 localiser des sites sp\u00e9cifiques o\u00f9 des syst\u00e8mes d&rsquo;assainissement autonomes peuvent se d\u00e9verser dans des rivi\u00e8res ou d&rsquo;autres cours d&rsquo;eau. Les sondes multiparam\u00e8tres \u00e9quip\u00e9es de capteurs OBA peuvent \u00eatre d\u00e9ploy\u00e9es pour une surveillance continue ou utilis\u00e9es pour un \u00e9chantillonnage discret. Les d\u00e9terminations fluorom\u00e9triques des concentrations d&rsquo;azurants dans les \u00e9chantillons d&rsquo;eau naturelle ont \u00e9t\u00e9 utiles pour trouver des sources d&rsquo;eaux us\u00e9es et des contaminations par des coliformes f\u00e9caux dans le cadre d&rsquo;\u00e9tudes men\u00e9es par le d\u00e9partement de la sant\u00e9, ainsi que dans le cadre de recherches g\u00e9n\u00e9rales.   <\/span><\/p>\n<p><span>L&rsquo;encrassement est le plus grand probl\u00e8me de terrain pour les capteurs de fluorescence. Tout mat\u00e9riau \u00e9tranger qui s&rsquo;accumule sur la surface active du capteur r\u00e9duit la quantit\u00e9 de lumi\u00e8re \u00e9mise ou re\u00e7ue, ou les deux. Et parfois, le mat\u00e9riau \u00e9tranger peut fournir un faux signal en produisant une fluorescence \u00e0 la m\u00eame longueur d&rsquo;onde. L&rsquo;encrassement ne pose g\u00e9n\u00e9ralement pas de probl\u00e8me lors de l&rsquo;\u00e9tablissement de profils ou de contr\u00f4les ponctuels dans le cadre d&rsquo;\u00e9tudes quotidiennes, mais seulement lors de d\u00e9ploiements prolong\u00e9s.    Pour un d\u00e9ploiement continu, des accessoires anti-salissures peuvent \u00eatre ajout\u00e9s, tels que le syst\u00e8me de raclage universel d&rsquo;Eureka et la protection du capteur en maille de cuivre.  <\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_color=\u00a0\u00bbRGBA(255,255,255,0)\u00a0\u00bb custom_css_free_form=\u00a0\u00bbwidth: 30%!important;\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb background_color__hover=\u00a0\u00bb\u00a0\u00bb background__hover_enabled=\u00a0\u00bbon|hover\u00a0\u00bb background_enable_color__hover=\u00a0\u00bboff\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/solinst-eureka-optical-brightener-sensors.webp\u00a0\u00bb alt=\u00a0\u00bbcapteurs optiques de qualit\u00e9 de l&#039;eau pour la surveillance de la pr\u00e9sence d&#039;azurants de nettoyage dans les eaux us\u00e9es\u00a0\u00bb title_text=\u00a0\u00bbCapteurs de qualit\u00e9 de l&#039;eau \u00e0 azurants optiques pour surveiller la pr\u00e9sence d&#039;azurants de nettoyage dans les eaux us\u00e9es\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb align_tablet=\u00a0\u00bbcenter\u00a0\u00bb align_phone=\u00a0\u00bbcenter\u00a0\u00bb align_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb20px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bbon|tablet\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00a0\u00bb4.27.6&Prime; _module_preset=\u00a0\u00bbb57ac812-3d5d-4cea-b758-2f6bee08b6f2&Prime; header_2_font_size=\u00a0\u00bb24px\u00a0\u00bb width=\u00a0\u00bb100%\u00a0\u00bb custom_margin=\u00a0\u00bb30px||||false|false\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<h2><strong>Capteurs \u00e0 azurant optique pour les sondes de qualit\u00e9 de l&rsquo;eau<br \/><\/strong><\/h2>\n<ul>\n<li><strong>Gamme<br \/><\/strong>0 \u00e0 300 ppb<\/li>\n<li><strong>Pr\u00e9cision<br \/><\/strong>lin\u00e9arit\u00e9 de 0,99 R\u00b2<\/li>\n<li><strong>R\u00e9solution<br \/><\/strong>0,01<\/li>\n<li><strong>Unit\u00e9s<\/strong><br \/>ppb<\/li>\n<li><strong>Calibration<br \/><\/strong>\u00e9chantillon qualifi\u00e9 pour le laboratoire<br \/>bouchon \u00e9talon solide secondaire (\u00ab\u00a0cal cube\u00a0\u00bb)<\/li>\n<li><strong>Entretien<br \/><\/strong>nettoyage et \u00e9talonnage<\/li>\n<li><strong>Dur\u00e9e de vie du capteur<\/strong><br \/>5+ ans<\/li>\n<li><strong>Type de capteur<br \/><\/strong>fluorescence<\/li>\n<\/ul>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1ODA3In19@\u00a0\u00bb button_text=\u00a0\u00bbObtenir un devis\u00a0\u00bb admin_label=\u00a0\u00bbget quote button\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbc9e00792-1360-4998-8cf9-5f6772c944ba\u00a0\u00bb global_module=\u00a0\u00bb46404&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb40px||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong>Caract\u00e9ristiques et avantages des capteurs d&rsquo;azurants optiques de Solinst Eureka<br \/><\/strong><\/h2>\n<p><a href=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plumultiparameter-probes\/\" title=\"Sondes multiparam\u00e8tres Solinst Eureka MantaPlus\"><strong>Sondes multiparam\u00e8tres Solinst Eureka MantaPlus<\/strong><\/a> peuvent \u00eatre configur\u00e9es pour inclure n&rsquo;importe lequel de nos fluorom\u00e8tres. Le capteur OBA peut \u00eatre install\u00e9 dans la sonde, avec d&rsquo;autres capteurs tels que des fluorom\u00e8tres suppl\u00e9mentaires, la turbidit\u00e9, l&rsquo;oxyg\u00e8ne dissous, le pH et la conductivit\u00e9. Il s&rsquo;agit d&rsquo;une approche rentable, puisqu&rsquo;il n&rsquo;est pas n\u00e9cessaire d&rsquo;acheter un syst\u00e8me de fluorim\u00e8tre sp\u00e9cifique. Le fonctionnement est facilit\u00e9 par le fait que le capteur OBA est contr\u00f4l\u00e9 par le logiciel Manta Control, comme les autres capteurs install\u00e9s. Lorsque seul le capteur OBA est n\u00e9cessaire, il peut \u00e9galement \u00eatre install\u00e9 de mani\u00e8re autonome sur l&rsquo;une des plus petites sondes d&rsquo;Eureka, comme le Trimeter.    <\/p>\n<p>Sondes multiples Manta Plus et <a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/sondes-de-qualite-de-leau\/trimeter\/\" title=\"Trimeter : Sonde de qualit\u00e9 de l'eau\"><strong>Trimeter Multiprobes<\/strong><\/a> peuvent \u00eatre configur\u00e9es avec des batteries pour un d\u00e9ploiement autonome, utilis\u00e9es avec des \u00e9crans de terrain pour des v\u00e9rifications ponctuelles d&rsquo;un site \u00e0 l&rsquo;autre, ou connect\u00e9es \u00e0 des stations de t\u00e9l\u00e9m\u00e9trie pour une surveillance \u00e0 distance en temps r\u00e9el. Les sondes Eureka \u00e9quip\u00e9es de fluorom\u00e8tres sont portables, durables et rentables. <\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbf0ff9324-d775-4951-8fd2-7c0df1fe47a5&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1ODA3In19@\u00a0\u00bb button_text=\u00a0\u00bbObtenir un devis\u00a0\u00bb admin_label=\u00a0\u00bbget quote button\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbc9e00792-1360-4998-8cf9-5f6772c944ba\u00a0\u00bb global_module=\u00a0\u00bb46404&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||9px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner saved_specialty_column_type=\u00a0\u00bb3_4&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2><strong>Produits apparent\u00e9s<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_margin=\u00a0\u00bb0px||1em||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb0px||0px||false|false\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-items: center;\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d3d3d3&Prime; global_module=\u00a0\u00bb69009&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-multi-parameter-probes.webp\u00a0\u00bb alt=\u00a0\u00bbsondes hydriques multiparam\u00e9triques solinst eureka\u00a0\u00bb title_text=\u00a0\u00bbSondes \u00e0 eau multiparam\u00e9triques Solinst Eureka\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MDM3In19@\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_color_all=\u00a0\u00bb#bcbcbc\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plumultiparameter-probes\/\" title=\"Sondes de qualit\u00e9 de l'eau de la s\u00e9rie Manta\">Sondes de qualit\u00e9 de l&rsquo;eau de la s\u00e9rie Manta<\/a><\/h3>\n<p><a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/\" title=\"Sondes de qualit\u00e9 de l'eau Solinst Eureka\"><strong>Solinst Eureka<\/strong><\/a><span>  offre la plus grande s\u00e9lection de technologies de capteurs de qualit\u00e9 de l&rsquo;eau de l&rsquo;industrie. Ainsi, en plus des configurations standard, chaque sonde peut \u00eatre personnalis\u00e9e pour votre application sp\u00e9cifique. Choisissez les capteurs de votre choix pour \u00e9quiper des sondes plus grandes, ou ajoutez une batterie pour convertir une sonde en dispositif d&rsquo;enregistrement. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MDM3In19@\u00a0\u00bb button_text=\u00a0\u00bbSondes de qualit\u00e9 de l&apos;eau Manta\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_color=\u00a0\u00bb#ff8500&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-items: center;\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d3d3d3&Prime; global_module=\u00a0\u00bb69010&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-trimeter-water-quality-sonde-965&#215;500-1.webp\u00a0\u00bb alt=\u00a0\u00bbsondes de qualit\u00e9 de l&#039;eau solinst eureka trimeter\u00a0\u00bb title_text=\u00a0\u00bbSondes de qualit\u00e9 de l&#039;eau Solinst Eureka Trimeter\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY0OTQwIn19@\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_color_all=\u00a0\u00bb#bcbcbc\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb link_option_url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/103-tag-line\/\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/sondes-de-qualite-de-leau\/trimeter\/\" title=\"Sonde de qualit\u00e9 de l'eau Manta Trimeter\">Sonde de qualit\u00e9 de l&rsquo;eau Manta Trimeter<\/a><\/h3>\n<p><span>Les <a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/sondes-de-qualite-de-leau\/trimeter\/\" title=\"Sonde de qualit\u00e9 de l'eau \u00e0 faible co\u00fbt Trimeter\"><strong>Trimeter<\/strong><\/a> peut contenir n&rsquo;importe quel capteur* de la liste des param\u00e8tres du capteur, plus les capteurs de temp\u00e9rature et de profondeur (les deux sont optionnels). Par exemple, une configuration Trimeter pourrait \u00eatre la turbidit\u00e9, la temp\u00e9rature et la profondeur.  Un autre exemple pourrait \u00eatre l&rsquo;OD et la temp\u00e9rature.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY0OTQwIn19@\u00a0\u00bb button_text=\u00a0\u00bbSonde de qualit\u00e9 de l&apos;eau Manta Trimeter\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_color=\u00a0\u00bb#ff8500&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-items: center;\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d3d3d3&Prime; global_module=\u00a0\u00bb69121&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-easyprobe-water-quality-sondes.webp\u00a0\u00bb alt=\u00a0\u00bbsondes de qualit\u00e9 de l&#039;eau solinst eureka easyprobe\u00a0\u00bb title_text=\u00a0\u00bbSondes de qualit\u00e9 de l&#039;eau Solinst Eureka EasyProbe\u00a0\u00bb url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MTQ3In19@\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bburl\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_color_all=\u00a0\u00bb#bcbcbc\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/sondes-de-qualite-de-leau\/sonde-de-qualite-de-leau-easyprobe\/\" title=\"EasyProbe : Sondes de qualit\u00e9 de l'eau\">EasyProbe : Sondes de qualit\u00e9 de l&rsquo;eau<\/a><\/h3>\n<p><span>Les <a href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/sondes-de-qualite-de-leau\/sonde-de-qualite-de-leau-easyprobe\/\" title=\"Sonde de qualit\u00e9 de l'eau EasyProbe\"><strong>EasyProbe<\/strong><\/a>de Solinst Eureka, est un moniteur de qualit\u00e9 de l&rsquo;eau tr\u00e8s performant et rentable. Il est id\u00e9al pour les contr\u00f4les ponctuels, la t\u00e9l\u00e9m\u00e9trie \u00e0 distance, l&rsquo;\u00e9ducation, la recherche, l&rsquo;aquaculture, etc. L&rsquo;EasyProbe20 comprend des capteurs de temp\u00e9rature, d&rsquo;oxyg\u00e8ne dissous, de conductivit\u00e9 et de pH, tandis que l&rsquo;EasyProbe30 ajoute un capteur de turbidit\u00e9.   Les multiprobes Eureka sont r\u00e9put\u00e9es pour leur fiabilit\u00e9, avec une garantie de trois ans couvrant tous les capteurs, et ont les co\u00fbts de maintenance les plus bas de l&rsquo;industrie.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bb@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MTQ3In19@\u00a0\u00bb button_text=\u00a0\u00bbSondes de qualit\u00e9 de l&apos;eau Manta Easy Probe\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _dynamic_attributes=\u00a0\u00bbbutton_url\u00a0\u00bb _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_color=\u00a0\u00bb#ff8500&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-items: center;\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d3d3d3&Prime; global_module=\u00a0\u00bb44627&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-levelogger-5-ltc.webp\u00a0\u00bb alt=\u00a0\u00bbsolinst levelogger 5 ltc niveau d&#039;eau temp\u00e9rature de l&#039;eau et conductivit\u00e9 de l&#039;eau datalogger\u00a0\u00bb title_text=\u00a0\u00bbSolinst Levelogger 5 Ltc Niveau d&#039;eau Temp\u00e9rature de l&#039;eau et conductivit\u00e9 de l&#039;eau Datalogger\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb border_color_all=\u00a0\u00bb#bcbcbc\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>Enregistrement du niveau d&rsquo;eau, de la temp\u00e9rature et de la conductivit\u00e9<\/h3>\n<p>Le <a href=\"https:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/\" title=\"Levelogger 5 LTC Level Enregistreur de temp\u00e9rature et de conductivit\u00e9\"><strong>Levelogger 5 LTC<\/strong><\/a> mesure et enregistre les fluctuations du niveau d&rsquo;eau, la temp\u00e9rature et la conductivit\u00e9. Il est programm\u00e9 pour enregistrer \u00e0 des intervalles allant jusqu&rsquo;\u00e0 2 secondes. Il est \u00e9quip\u00e9 d&rsquo;une pile de 8 ans, d&rsquo;une m\u00e9moire pour 100 000 relev\u00e9s et est disponible en 6 gammes de pression. Un rev\u00eatement sans PFAS (\u00e0 l&rsquo;int\u00e9rieur et \u00e0 l&rsquo;ext\u00e9rieur) offre une r\u00e9sistance sup\u00e9rieure \u00e0 la corrosion et \u00e0 l&rsquo;abrasion.   <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/\u00a0\u00bb button_text=\u00a0\u00bbEnregistreur de conductivit\u00e9 polyvalent\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_color=\u00a0\u00bb#ff8500&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=\u00a0\u00bb1_2,1_2&Prime; make_equal=\u00a0\u00bbon\u00a0\u00bb disabled_on=\u00a0\u00bboff|off|off\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_css_main_element=\u00a0\u00bbalign-items: center;\u00a0\u00bb border_width_bottom=\u00a0\u00bb1px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#d3d3d3&Prime; global_module=\u00a0\u00bb44750&Prime; saved_tabs=\u00a0\u00bball\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_image src=\u00a0\u00bbhttps:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/107-tlc-meter.webp\u00a0\u00bb alt=\u00a0\u00bbsolinst model 107 tlc meter for temperature and conductivity profiling\u00a0\u00bb title_text=\u00a0\u00bbSolinst Model 107 Tlc Meter For Temperature And Conductivity Profiling\u00a0\u00bb url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/\u00a0\u00bb align=\u00a0\u00bbcenter\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bb100%\u00a0\u00bb border_color_all=\u00a0\u00bb#bcbcbc\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=\u00a0\u00bb1_2&Prime; _builder_version=\u00a0\u00bb4.25.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_2_line_height=\u00a0\u00bb1.3em\u00a0\u00bb custom_margin_tablet=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_phone=\u00a0\u00bb0px||||false|false\u00a0\u00bb custom_margin_last_edited=\u00a0\u00bboff|desktop\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h3>TLC Meter &#8211; Mesure pr\u00e9cise de la temp\u00e9rature, du niveau et de la conductivit\u00e9<\/h3>\n<p>A <a href=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/\" title=\"TLC Meter Temp\u00e9rature de l'eau et profil de conductivit\u00e9 de l'eau\"><strong>TLC Meter<\/strong><\/a> fournit des mesures de temp\u00e9rature et de conductivit\u00e9 pr\u00e9cises et stables, affich\u00e9es sur un \u00e9cran LCD pratique pour une lecture ais\u00e9e. Le niveau d&rsquo;eau statique et la profondeur des relev\u00e9s sont lus sur le ruban plat Solinst, qui est marqu\u00e9 au laser avec pr\u00e9cision tous les mm ou 1\/100 ft. Les longueurs de ruban sont disponibles jusqu&rsquo;\u00e0 300 m (1000 ft).  <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00a0\u00bbhttps:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/\u00a0\u00bb button_text=\u00a0\u00bbProfilage de la temp\u00e9rature et de la conductivit\u00e9\u00a0\u00bb button_alignment=\u00a0\u00bbleft\u00a0\u00bb button_alignment_tablet=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_phone=\u00a0\u00bbcenter\u00a0\u00bb button_alignment_last_edited=\u00a0\u00bbon|phone\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_button=\u00a0\u00bbon\u00a0\u00bb button_text_size=\u00a0\u00bb18px\u00a0\u00bb button_text_color=\u00a0\u00bb#000000&Prime; button_bg_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb button_border_color=\u00a0\u00bb#ff8500&Prime; button_border_radius=\u00a0\u00bb20px\u00a0\u00bb button_icon=\u00a0\u00bb&#x3d;||divi||400&Prime; custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbAdobe Analytics Code\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb custom_padding=\u00a0\u00bb||4px|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.27.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.27.0&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_code admin_label=\u00a0\u00bbCode AA pour cette page\u00a0\u00bb _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<!-- SiteCatalyst code version: H.21. Copyright 1996-2010 Adobe, Inc. All Rights Reserved More info available at http:\/\/www.omniture.com --><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\" src=\"\/\/www.solinst.com\/s_code.js\"><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->s.pageName=\"5001 optical brightener sensors\"<!-- [et_pb_line_break_holder] -->s.server=\"\"<!-- [et_pb_line_break_holder] -->s.channel=\"products\"<!-- [et_pb_line_break_holder] -->s.pageType=\"\"<!-- [et_pb_line_break_holder] -->s.prop1=\"solinst eureka\"<!-- [et_pb_line_break_holder] -->s.prop2=\"5001 water quality sensors\"<!-- [et_pb_line_break_holder] -->s.prop3=\"5001 fluorometers\"<!-- [et_pb_line_break_holder] -->s.prop4=\"5001 optical brightener sensors\"<!-- [et_pb_line_break_holder] -->s.prop5=\"\"<!-- [et_pb_line_break_holder] -->s.prop6=\"\"<!-- [et_pb_line_break_holder] -->s.prop7=\"\"<!-- [et_pb_line_break_holder] -->s.prop8=\"\"<!-- [et_pb_line_break_holder] -->s.prop9=\"\"<!-- [et_pb_line_break_holder] -->s.prop10=\"\"<!-- [et_pb_line_break_holder] -->s.prop11=\"\"<!-- [et_pb_line_break_holder] -->s.prop12=\"\"<!-- [et_pb_line_break_holder] -->s.prop13=\"\"<!-- [et_pb_line_break_holder] -->s.prop14=\"\"<!-- [et_pb_line_break_holder] -->s.prop15=\"\"<!-- [et_pb_line_break_holder] -->s.prop16=\"\"<!-- [et_pb_line_break_holder] -->s.prop17=\"\"<!-- [et_pb_line_break_holder] -->s.prop18=\"\"<!-- [et_pb_line_break_holder] -->s.prop19=\"\"<!-- [et_pb_line_break_holder] -->s.prop20=\"\"<!-- [et_pb_line_break_holder] -->s.prop21=\"\"<!-- [et_pb_line_break_holder] -->s.prop22=\"\"<!-- [et_pb_line_break_holder] -->s.prop23=\"\"<!-- [et_pb_line_break_holder] -->s.prop24=\"\"<!-- [et_pb_line_break_holder] -->s.prop25=\"\"<!-- [et_pb_line_break_holder] -->s.prop26=\"\"<!-- [et_pb_line_break_holder] -->s.prop27=\"\"<!-- [et_pb_line_break_holder] -->s.prop28=\"\"<!-- [et_pb_line_break_holder] -->s.prop29=\"\"<!-- [et_pb_line_break_holder] -->s.prop30=\"\"<!-- [et_pb_line_break_holder] -->s.prop31=\"\"<!-- [et_pb_line_break_holder] -->s.prop32=\"\"<!-- [et_pb_line_break_holder] -->s.prop33=\"\"<!-- [et_pb_line_break_holder] -->s.hier1=\"solinst:products:solinst eureka:5001 water quality sensors:5001 fluorometers:5001 optical brightener sensors\"<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/* Conversion Variables *\/<!-- [et_pb_line_break_holder] -->s.campaign=\"\"<!-- [et_pb_line_break_holder] -->s.events=\"\"<!-- [et_pb_line_break_holder] -->s.eVar1=\"\"<!-- [et_pb_line_break_holder] -->s.eVar2=\"\"<!-- [et_pb_line_break_holder] -->s.eVar3=\"\"<!-- [et_pb_line_break_holder] -->s.eVar4=\"\"<!-- [et_pb_line_break_holder] -->s.eVar5=\"\"<!-- [et_pb_line_break_holder] -->s.eVar6=\"\"<!-- [et_pb_line_break_holder] -->s.eVar7=\"\"<!-- [et_pb_line_break_holder] -->s.eVar8=\"\"<!-- [et_pb_line_break_holder] -->s.eVar9=\"\"<!-- [et_pb_line_break_holder] -->s.eVar10=\"\"<!-- [et_pb_line_break_holder] -->s.eVar11=\"\"<!-- [et_pb_line_break_holder] -->s.eVar12=\"\"<!-- [et_pb_line_break_holder] -->s.eVar13=\"\"<!-- [et_pb_line_break_holder] -->s.eVar14=\"\"<!-- [et_pb_line_break_holder] -->s.eVar15=\"\"<!-- [et_pb_line_break_holder] -->s.eVar16=\"\"<!-- [et_pb_line_break_holder] -->s.eVar17=\"\"<!-- [et_pb_line_break_holder] -->s.state=\"\"<!-- [et_pb_line_break_holder] -->s.zip=\"\"<!-- [et_pb_line_break_holder] -->\/************* DO NOT ALTER ANYTHING BELOW THIS LINE ! **************\/<!-- [et_pb_line_break_holder] -->var s_code=s.t();if(s_code)document.write(s_code)\/\/--><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->if(navigator.appVersion.indexOf('MSIE')>=0)document.write(unescape('%3C')+'!-'+'-')<!-- [et_pb_line_break_holder] -->\/\/--><\/script><noscript><a href=\"https:\/\/www.omniture.com\" title=\"Analyse du Web\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solinst.d2.sc.omtrdc.net\/b\/ss\/solinst-prod\/1\/H.21--NS\/0\" height=\"1\" width=\"1\" border=\"0\" alt=\"\"><\/a><\/noscript><!--\/DO NOT REMOVE\/--><!-- [et_pb_line_break_holder] --><!-- End SiteCatalyst code version: H.21. -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p><div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"https:\/\/www.solinst.com\/fr\/\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"et-pb-icon dsm_home_icon\">\ue009<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\tHome\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">5<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div> Solinst Eureka2113 Wells Branch Pkwy, Suite 4400Austin, TX, USA78728 Tel: +1 512-302-4333Fax: +1 512-251-6842email: eureka@solinst.com &nbsp; Donn\u00e9es pr\u00e9cises sur le niveau de l&rsquo;eau Des instruments fiables qui durent&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;<div class=\"et_pb_module dsm_icon_list dsm_icon_list_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<ul class=\"dsm_icon_list_items dsm_icon_list_ltr_direction dsm_icon_list_layout_vertical\"><li class=\"dsm_icon_list_child dsm_icon_list_child_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/www.solinst.com\/products\/data\/5001-fluorometers.pdf\" target=\"_blank\"><span class=\"dsm_icon_list_wrapper\"><span class=\"dsm_icon_list_icon\">\uf1c1<\/span><\/span><span class=\"dsm_icon_list_text\">5001 Fluorom\u00e8tres PDF<\/span><\/a>\n\t\t\t<\/li><\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>Pourquoi voudrais-je mesurer les azurants optiques ? Les azurants optiques (OBA) ou les agents de blanchiment fluorescents (FWA) sont ajout\u00e9s \u00e0 des produits tels que les savons de lessive, les d\u00e9tergents ou les agents de nettoyage. Les tissus ou les mat\u00e9riaux absorbent les OBA au cours du processus de lavage ou de nettoyage. Lorsqu&rsquo;ils sont \u00e9clair\u00e9s par une lumi\u00e8re ultraviolette, ils deviennent fluorescents et font para\u00eetre les produits et les tissus plus brillants. Les eaux us\u00e9es des blanchisseries sont le plus gros contributeur d&rsquo;azurants dans les syst\u00e8mes d&rsquo;assainissement. Les contributions FWA ou OBA au volume total de la plupart des d\u00e9tergents de blanchisserie sont inf\u00e9rieures \u00e0 0,5 %, mais une grande partie (5-80 %) peut rester dans les eaux us\u00e9es rejet\u00e9es sous forme de compos\u00e9s dissous (mol\u00e9culaires). La pr\u00e9sence d&rsquo;azurants dans les syst\u00e8mes d&rsquo;eau dans lesquels les eaux [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":103387,"parent":64066,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"folder":[310],"class_list":["post-67027","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Capteurs \u00e0 azurant optique : Surveillance de la qualit\u00e9 de l&#039;eau<\/title>\n<meta name=\"description\" content=\"Capteurs \u00e0 azurant optique : La surveillance de la qualit\u00e9 de l&#039;eau peut \u00eatre install\u00e9e avec des capteurs de turbidit\u00e9, d&#039;oxyg\u00e8ne dissous, de pH et de conductivit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capteurs d&#039;azurants optiques Solinst Eureka\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez l&#039;importance des capteurs d&#039;azurants optiques dans la d\u00e9tection des contaminants provenant du linge et d&#039;autres processus pour un environnement plus propre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T18:57:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/06\/featureimages-eureka-fluorometric-sensor.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Capteurs d&#039;azurants optiques Solinst Eureka\" \/>\n<meta name=\"twitter:description\" content=\"D\u00e9couvrez l&#039;importance des capteurs d&#039;azurants optiques dans la d\u00e9tection des contaminants provenant du linge et d&#039;autres processus pour un environnement plus propre.\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"26 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/\",\"name\":\"Capteurs \u00e0 azurant optique : Surveillance de la qualit\u00e9 de l'eau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/featureimages-eureka-fluorometric-sensor.webp\",\"datePublished\":\"2025-03-06T13:57:56+00:00\",\"dateModified\":\"2026-05-28T18:57:42+00:00\",\"description\":\"Capteurs \u00e0 azurant optique : La surveillance de la qualit\u00e9 de l'eau peut \u00eatre install\u00e9e avec des capteurs de turbidit\u00e9, d'oxyg\u00e8ne dissous, de pH et de conductivit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/featureimages-eureka-fluorometric-sensor.webp\",\"contentUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/featureimages-eureka-fluorometric-sensor.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/capteurs-de-qualite-de-leau\\\/capteurs-dazurants-optiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solinst Eureka\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/produits\\\/solinst-eureka\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Capteurs de qualit\u00e9 de l&#8217;eau\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/instruments\\\/solinst-eureka\\\/water-quality-sensors\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Capteurs d&#8217;azurants optiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/\",\"name\":\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\",\"description\":\"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solinst.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Capteurs \u00e0 azurant optique : Surveillance de la qualit\u00e9 de l'eau","description":"Capteurs \u00e0 azurant optique : La surveillance de la qualit\u00e9 de l'eau peut \u00eatre install\u00e9e avec des capteurs de turbidit\u00e9, d'oxyg\u00e8ne dissous, de pH et de conductivit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Capteurs d'azurants optiques Solinst Eureka","og_description":"D\u00e9couvrez l'importance des capteurs d'azurants optiques dans la d\u00e9tection des contaminants provenant du linge et d'autres processus pour un environnement plus propre.","og_url":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/","og_site_name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","article_modified_time":"2026-05-28T18:57:42+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/06\/featureimages-eureka-fluorometric-sensor.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Capteurs d'azurants optiques Solinst Eureka","twitter_description":"D\u00e9couvrez l'importance des capteurs d'azurants optiques dans la d\u00e9tection des contaminants provenant du linge et d'autres processus pour un environnement plus propre.","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"26 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/","url":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/","name":"Capteurs \u00e0 azurant optique : Surveillance de la qualit\u00e9 de l'eau","isPartOf":{"@id":"https:\/\/www.solinst.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/#primaryimage"},"image":{"@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/06\/featureimages-eureka-fluorometric-sensor.webp","datePublished":"2025-03-06T13:57:56+00:00","dateModified":"2026-05-28T18:57:42+00:00","description":"Capteurs \u00e0 azurant optique : La surveillance de la qualit\u00e9 de l'eau peut \u00eatre install\u00e9e avec des capteurs de turbidit\u00e9, d'oxyg\u00e8ne dissous, de pH et de conductivit\u00e9.","breadcrumb":{"@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/#primaryimage","url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/06\/featureimages-eureka-fluorometric-sensor.webp","contentUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/06\/featureimages-eureka-fluorometric-sensor.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/capteurs-de-qualite-de-leau\/capteurs-dazurants-optiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.solinst.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.solinst.com\/fr\/produits\/"},{"@type":"ListItem","position":3,"name":"Solinst Eureka","item":"https:\/\/www.solinst.com\/fr\/produits\/solinst-eureka\/"},{"@type":"ListItem","position":4,"name":"Capteurs de qualit\u00e9 de l&#8217;eau","item":"https:\/\/www.solinst.com\/fr\/instruments\/solinst-eureka\/water-quality-sensors\/"},{"@type":"ListItem","position":5,"name":"Capteurs d&#8217;azurants optiques"}]},{"@type":"WebSite","@id":"https:\/\/www.solinst.com\/fr\/#website","url":"https:\/\/www.solinst.com\/fr\/","name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","description":"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solinst.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/pages\/67027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/comments?post=67027"}],"version-history":[{"count":0,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/pages\/67027\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/pages\/64066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/media\/103387"}],"wp:attachment":[{"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/media?parent=67027"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.solinst.com\/fr\/wp-json\/wp\/v2\/folder?post=67027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}