{"id":67795,"date":"2025-03-07T14:40:46","date_gmt":"2025-03-07T14:40:46","guid":{"rendered":"https:\/\/www.solinst.com\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/"},"modified":"2026-05-13T21:26:43","modified_gmt":"2026-05-13T21:26:43","slug":"elettrodi-selettivi-ionici-ise","status":"publish","type":"page","link":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/","title":{"rendered":"Elettrodi selettivi ionici ISE"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_fullwidth_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/solinst-eureka-water-quality-sensors-1920&#215;500-1.webp&#8221; alt=&#8221;sensori di qualit\u00e0 dell&#039;acqua solinst eureka&#8221; title_text=&#8221;Sensori di qualit\u00e0 dell&#039;acqua Solinst Eureka&#8221; src_tablet=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/solinst-eureka-water-quality-sensors-965&#215;500-1.webp&#8221; src_phone=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/solinst-eureka-water-quality-sensors-965&#215;500-1.webp&#8221; src_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_fullwidth_image][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;H1 and breadcrumbs&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;792ca5bd-0808-46bd-9ce7-3bcb8e74f4d3&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;4b28f470-0d73-4e9d-b92d-e6f41f2cea24&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;3078f328-b50a-467d-9906-3143dabcd7ac&#8221; header_text_align_tablet=&#8221;&#8221; header_text_align_phone=&#8221;&#8221; header_text_align_last_edited=&#8221;on|desktop&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;26px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 role=\"heading\" aria-level=\"2\" data-uw-rm-heading=\"level\">Elettrodi selettivi ionici ISE<\/h1>\n<p>[\/et_pb_text][dsm_breadcrumbs disabled_on=&#8221;on|off|off&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; home_icon_text_color=&#8221;#d6d6d6&#8243; global_colors_info=&#8221;{}&#8221;][\/dsm_breadcrumbs][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Mobile-Only Nav with Offset&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;4759a92f-4b27-4854-bb2c-299854634e93&#8243; sticky_offset_top=&#8221;127px&#8221; global_module=&#8221;45704&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_margin=&#8221;0px||||false|false&#8221; custom_padding=&#8221;0px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;Eureka Mobile Nav &#8211; Seleziona il menu a tendina&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_css_free_form=&#8221;select {||||      font-size: 1em; \/* Adjust font size *\/||      padding: 10px;   \/* Optional: Increase padding for better spacing *\/||      width: 100%;||      box-sizing: border-box;\/* Optional: Adjust width to fit the container *\/||      height: 50px;||}||||    \/* Style for dropdown options (fallback if needed) *\/||select option {||      font-size: 1.2em; \/* Ensures option text matches select styling *\/||      width: 100%;||    }&#8221; global_colors_info=&#8221;{}&#8221;]<select name=\"dropdown\" onchange=\"location = this.value;\"><!-- [et_pb_line_break_holder] --><option value=\"\">Menu Solinst Eureka<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/\">Pagina principale di Solinst Eureka<\/option><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/\">Sonde per la qualit\u00e0 dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/\">-Sonde multiparametriche Manta<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-20-multiparameter-probes\/\">-Manta Plus 20<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-25-multiparameter-probes\/\">-Manta Plus 25<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-30-multiparameter-probe\/\">&#8211;Manta Plus 30<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-35-multiparameter-probes\/\">-Manta Plus 35<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-f35-multiparameter-water-quality-probes\/\">&#8211;Manta F35<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plus-multi-parameter-probes\/manta-plus-40-multiparameter-probe\/\">-Manta Plus 40<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/\">-Trimetro<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/datasheet\/\">&#8211;Scheda tecnica<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/trimeter\/5001-trimeter-sonde-quote-form\/\">&#8211;Richiedi un preventivo<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/\">-Sonda per la qualit\u00e0 dell&#8217;acqua EasyProbe<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/datasheet\/\">&#8211;Scheda tecnica<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/easy-probe\/5001-easyprobe-sondes-quote-form\/\">&#8211;Richiedi un preventivo<\/option><!-- [et_pb_line_break_holder] -->        <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/\">Sensori di qualit\u00e0 dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/temperature-sensor\/\">-Sensore di temperatura<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ph-sensors\/\">-Sensori di pH<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/orp-oxidation-reduction-potential-sensors\/\">-Sensore ORP<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/turbidity-sensors\/\">-Sensori di torbidit\u00e0<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/dissolved-oxygen-sensors\/\">-Sensori di ossigeno disciolto<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/conductivity-sensors\/\">-Sensori di conduttivit\u00e0<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/transmittance-sensors\/\">-Sensori di trasmittanza<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/pressure-sensors\/\">-Sensori di pressione<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/total-dissolved-gas-sensors\/\">-Sensori di gas disciolto totale<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/c02-carbon-dioxide-sensors\/\">Sensori di anidride carbonica -CO2<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/par-photosynthetically-active-radiation-sensors\/\">Sensori di radiazione attiva fotosintetica -PAR<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/fluorometers\/\">-Fluorimetri<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/chlorophyll-sensors\/\">&#8211;Sensori di clorofilla<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/blue-green-algae-sensors\/\">&#8211;Sensori di alghe verdi blu<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/cdom-colored-dissolved-organic-matter-sensors\/\">&#8211;Sensori di materia organica disciolta colorati CDOM<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/optical-brightener-sensors\/\">&#8211;Sensori ottici di luminosit\u00e0<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/tryptophan-sensors\/\">&#8211;Sensori di triptofano<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/rhodamine-sensors\/\">&#8211;Sensori alla rodamina<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/flourescein-sensors\/\">&#8211;Sensori di fluoresceina<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ptsa-fluorescence-sensors\/\">&#8211;Sensori di fluorescenza PTSA<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/refined-oil-and-fuel-sensors\/\">&#8211;Sensori di olio e carburante definiti<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/crude-oil-sensors\/\">&#8211;Sensori di petrolio greggio<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/ise-ion-selective-electrodes\/\">Elettrodi selettivi di ioni -ISE<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sensors\/water-quality-sensor-configurations\/\">-Configurazioni dei sensori di qualit\u00e0 dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] -->    <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/\">Dispositivi e applicazioni da campo rugged<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-mobile-wireless-data-device\/\">-mantaMobile<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-mobile-wireless-data-device\/datasheet\/\">&#8211;Scheda tecnica<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/manta-link-app\/\">-MantaLink<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/\">-Compresse rinforzate<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/samsung-galaxy-tab-active3\/\">&#8211;Samsung Galaxy Tab Active3<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/juniper-systems-mesa3\/\">&#8211;Sistemi Juniper MESA3<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/ipad-mini-ruggedized-tablet\/\">&#8211;Tablet iPad Mini rinforzato<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/ruggedized-tablets-for-water-quality-monitoring\/juniper-cedar-ct8x2\/\">&#8212; Tavolo ruggedizzato CT8X2 in cedro di ginepro<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/rugged-field-devices-and-apps-for-water-quality-data-collection\/remote-water-quality-monitoring\/\">-Monitoraggio a distanza della qualit\u00e0 dell&#8217;acqua  <\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-monitoring-accessories\/\">Accessori per il monitoraggio della qualit\u00e0 dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-monitoring-applications\/\">Applicazioni di monitoraggio della qualit\u00e0 dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] -->   <!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/quote\/\">Richiedi un preventivo<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/contact\/\">Contattaci<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/distributors\/\">Distributori Solinst Eureka<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/support\/\">Supporto Solinst Eureka<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/support\/rma-return-material-authorization-form\/\">-Autorizzazione alla restituzione del materiale<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/maintenance-program\/\">Programma di manutenzione Solinst Eureka<\/option><!-- [et_pb_line_break_holder] -->\t<!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/\">Casi di successo di Solinst Eureka<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/manta-probes-monitor-water-quality-at-jellyfish-lake-palau\/\">-Sonde Manta utilizzate nel lago JellyFish<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/ut-dallas-disaster-team-uses-eureka-probes-in-dangerous-environments\/\">-Sonde Eureka utilizzate in ambienti pericolosi<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/solar-charged-continous-monitoring-in-rugged-conditions\/\">-SFPUC: Monitoraggio continuo a carica solare in condizioni difficili<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/scientists-monitor-water-in-everglades-with-hydrostation\/\">-Gli scienziati monitorano l&#8217;acqua nelle Everglades con una stazione idroelettrica in valigia<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/maintaining-water-quality-in-a-formerly-flammable-river\/\">-Mantenere la qualit\u00e0 dell&#8217;acqua in un fiume un tempo infiammabile<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/after-a-megafire-how-are-waterways-impacted-by-a-wildfire\/\">-BYU: Dopo un mega-incendio, come vengono influenzati i corsi d&#8217;acqua da un incendio selvaggio?<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/robots-used-to-analyze-aquatic-environments\/\">-UT: Robot utilizzati per analizzare gli ambienti acquatici<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/nps-eastern-river-and-mountains-network\/\">-Rete dei fiumi e delle montagne dell&#8217;est<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/remote-monitoring-for-early-warning-of-water-pollution-events\/\">-Monitoraggio a distanza per l&#8217;allerta precoce degli eventi di inquinamento idrico<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/turbidity-monitoring-establishes-baseline-data-prior-to-construction-activities\/\">-Monitoraggio della torbidit\u00e0 Dati di riferimento stabiliti prima delle attivit\u00e0 di costruzione<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/monitoring-in-high-hypolimnetic-sulfide-concentrations\/\">-Il profilatore verticale fornisce un monitoraggio continuo in presenza di alte concentrazioni di solfuro ipolimnetico<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/water-quality-monitoring-in-extreme-bio-fouling-conditions\/\">-Monitoraggio in continuo della qualit\u00e0 dell&#8217;acqua in condizioni estreme di bio-incrostazione<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/high-resolution-temporal-monitoring-of-an-arid-urban-lake\/\">-Monitoraggio temporale ad alta risoluzione di un lago urbano e arido<\/option><!-- [et_pb_line_break_holder] --><option value=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/success-cases\/water-reuse-model-research\/\">-Ricerca sui modelli di riutilizzo dell&#8217;acqua<\/option><!-- [et_pb_line_break_holder] -->  <!-- [et_pb_line_break_holder] --><\/select>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; specialty=&#8221;on&#8221; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;5a5bca26-a9a5-4e6c-8fca-d64da3bdcd40&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_menu menu_id=&#8221;252&#8243; admin_label=&#8221;Eureka Main Nav&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;242faa89-ac4f-4e46-90fe-505e8c1eab79&#8243; global_module=&#8221;45700&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_menu][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;10px||||false|false&#8221; global_module=&#8221;46733&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/solinst.com\/eureka\" title=\"Solinst Eureka\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-logo-800w.webp\" width=\"271\" height=\"49\" alt=\"solinst eureka logo\" class=\"wp-image-44307 alignnone size-full\" \/><\/strong><\/a><\/p>\n<p><strong>Solinst Eureka<\/strong><br \/>2113 Wells Branch Pkwy, Suite 4400<br \/>Austin, TX, USA<br \/>78728<\/p>\n<p>Tel: +1 512-302-4333<br \/>Fax: +1 512-251-6842<br \/>email: <a href=\"mailto:eureka@solinst.com\">eureka@solinst.com<\/a><\/p>\n<p>[\/et_pb_text][et_pb_slider disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; display_conditions=&#8221;W10=&#8221; link_option_url=&#8221;https:\/\/www.solinst.com\/instruments\/dataloggers-and-telemetry-systems\/3001-levelogger\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position1&#038;utm_campaign=3001&#8243; global_module=&#8221;53188&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_slide button_text=&#8221;Levelogger&#8221; button_link=&#8221;https:\/\/www.solinst.com\/it\/prodotti\/datalogger-e-sistemi-di-telemetria\/3001-levelogger\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position1&amp;utm_campaign=3001&#8243; use_bg_overlay=&#8221;on&#8221; bg_overlay_color=&#8221;rgba(224,97,0,0.58)&#8221; button_text_tablet=&#8221;&#8221; button_text_phone=&#8221;&#8221; button_text_last_edited=&#8221;on|desktop&#8221; content_tablet=&#8221;&#8221; content_phone=&#8221;&#8221; content_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F07C00&#8243; background_enable_color=&#8221;on&#8221; background_image=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-absolute-water-level-datalogging.webp&#8221; background_enable_image=&#8221;on&#8221; background_position=&#8221;top_center&#8221; custom_button=&#8221;on&#8221; button_bg_color=&#8221;#f58025&#8243; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#ffffff&#8221; button_border_radius=&#8221;20px&#8221; button_font=&#8221;|600|||||||&#8221; background_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221; button_border_width__hover_enabled=&#8221;on|hover&#8221; button_border_width__hover=&#8221;2px&#8221; sticky_transition=&#8221;on&#8221;]<\/p>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<h2><strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<h2>Dati accurati sul livello dell&#8217;acqua<\/h2>\n<p><b>Strumenti affidabili che durano nel tempo<\/b><\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][et_pb_slider disabled_on=&#8221;on|on|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;https:\/\/www.solinst.com\/careers\/?utm_source=solinst&#038;utm_medium=WC-global-sidebar-position2&#038;utm_campaign=SUK-regional-sales-manager&#8221; global_module=&#8221;53561&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_slide heading=&#8221;Solinst UK sta assumendo!&#8221; button_text=&#8221;Responsabile vendite regionali&#8221; button_link=&#8221;https:\/\/www.solinst.com\/careers\/?utm_source=solinst&amp;utm_medium=WC-global-sidebar-position2&amp;utm_campaign=SUK-regional-sales-manager&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;38px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; background_enable_color=&#8221;on&#8221; background_image=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2026\/04\/solinst-uk-ltd.webp&#8221; background_enable_image=&#8221;on&#8221; background_size=&#8221;contain&#8221; custom_button=&#8221;on&#8221; button_bg_color=&#8221;#f58025&#8243; button_border_width=&#8221;2px&#8221; button_border_color=&#8221;#ffffff&#8221; button_border_radius=&#8221;20px&#8221; button_font=&#8221;|600|||||||&#8221; button_custom_margin=&#8221;||||false|false&#8221; button_custom_padding=&#8221;1px||||false|false&#8221; custom_padding=&#8221;76px||||false|false&#8221; header_text_shadow_style=&#8221;preset5&#8243; global_colors_info=&#8221;{}&#8221; sticky_transition=&#8221;on&#8221;]<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; specialty_columns=&#8221;3&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;3676f7e6-7b83-4698-94ce-2cc9fa9ae43d&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Perch\u00e9 dovrei voler misurare ioni specifici?<\/strong><\/h2>\n<p>Gli elettrodi iono-selettivi (ISE) sono una classe di sensori che rispondono alla presenza di ioni specifici, come il sodio (Na+) o il bromuro (Br). Vengono utilizzati insieme a un elettrodo di riferimento e riportano le concentrazioni degli ioni in mg\/L. <\/p>\n<p>Gli ISE pi\u00f9 comuni misurano l&#8217;ammonio (NH4+), il nitrato (NO3-) o il cloruro (Cl-). L&#8217;ammonio e il nitrato sono importanti perch\u00e9 sono indicatori di nutrienti a base di azoto. Vengono spesso utilizzati per rilevare la contaminazione da parte di impianti di trattamento delle acque reflue o attivit\u00e0 agricole. Le misurazioni del cloruro sono spesso utilizzate come indicatori di contaminazione da parte dell&#8217;acqua di mare o di altre fonti di contaminazione che contengono livelli di cloruro superiori a quelli previsti nelle acque naturali. Sono disponibili circa 30 altri ISE; alcuni funzionano meglio di altri.    <\/p>\n<p>I cambiamenti nelle tendenze a lungo termine degli ioni specifici possono segnalare la necessit\u00e0 di uno studio chimico pi\u00f9 dettagliato dell&#8217;acqua e delle sue fonti di contaminazione.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Come si misurano gli ioni specifici?<\/strong><\/h2>\n<p>Esistono due tipi di ISE. Gli ISE &#8220;a stato solido&#8221; sono costituiti da un blocco di materiale solido. Un esempio \u00e8 il sensore di cloruro, che \u00e8 poco pi\u00f9 di un piccolo pezzo di argento. Concentrazioni diverse di ioni cloruro producono potenziali di tensione diversi sulla superficie dell&#8217;argento e queste tensioni vengono misurate utilizzando lo stesso elettrodo di riferimento di un sensore di pH.   <\/p>\n<p>Le ISE a &#8220;membrana liquida&#8221; sono costituite da una sottile membrana polimerica che ricopre un elettrolita contenente un filo elettrodico. La membrana \u00e8 &#8220;drogata&#8221; con vari materiali che rispondono alla presenza di specifici ioni, creando un potenziale di tensione correlato alla concentrazione dello ione. Come per le ISE a stato solido, queste tensioni vengono misurate utilizzando lo stesso elettrodo di riferimento di un sensore di pH.  <\/p>\n<p>Purtroppo, molti sensori di ioni specifici non sono particolarmente specifici. Gli ISE di ammonio, ad esempio, subiscono interferenze da parte di ioni di dimensioni e carica simili (+1). Il potassio \u00e8 un interferente minore (di solito) nell&#8217;acqua dolce, ma nell&#8217;acqua di mare gli ioni di sodio spesso causano una falsa lettura fino a 12 mg\/l-N di ammonio anche se non \u00e8 presente ammonio.  <\/p>\n<p>Per questo motivo, i sensori di ammonio e nitrato non funzionano in acqua di mare.<\/p>\n<p>Alcune specie ioniche sono influenzate dal pH dell&#8217;acqua campione. L&#8217;ammonio, ad esempio, si converte in ammoniaca gassosa (NH3) a pH elevati (il pKa dell&#8217;ammonio-ammoniaca \u00e8 9,3). Questo fenomeno non \u00e8 legato al funzionamento dell&#8217;ISE, ma misurando l&#8217;ammonio con un ISE e misurando il pH, puoi calcolare la concentrazione di ammoniaca e l&#8217;ammoniaca totale (ammonio pi\u00f9 ammoniaca) in unit\u00e0 di mg\/L-N (cio\u00e8 mg\/l di azoto sotto forma di ammonio o ammoniaca). Questo \u00e8 comodo quando si opera a pH elevati dove \u00e8 probabile che siano presenti sia specie di ammoniaca che di ammonio.   <\/p>\n<p>Gli ISE sono facili da calibrare, a meno che tu non voglia farlo bene. Ci\u00f2 comporta una calibrazione a quattro punti per una maggiore precisione: due concentrazioni a due temperature. La maggior parte delle persone sceglie invece di calibrare con due concentrazioni a una temperatura vicina a quella prevista per le misurazioni effettive. Segui le istruzioni dello strumento. Sono disponibili standard di calibrazione per molte concentrazioni diverse.    <\/p>\n<p>La maggior parte degli ISE si avvita al ricevitore con un semplice o-ring di tenuta. In questo modo \u00e8 facile cambiare le punte dei sensori quando la loro durata si esaurisce. Rev &#8211; 9.20 Consulta la sezione &#8220;La differenza tra attivit\u00e0 e concentrazione nella calibrazione degli elettrodi ionoselettivi&#8221; per capire come si utilizzano gli standard di calibrazione.  <\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Cosa devo sapere sulla misurazione ISE sul campo?<\/strong><\/h2>\n<p>Gli ISE tendono a uscire dalle specifiche di precisione prima di accumulare incrostazioni. Ogni utente deve valutare le prestazioni di un ISE in situazioni particolari per determinare per quanto tempo pu\u00f2 funzionare prima di superare l&#8217;intervallo di precisione desiderato. \u00c8 meglio non lasciare che il tuo ISE si asciughi, quindi metti una piccola quantit\u00e0 di acqua di rubinetto nella tazza di conservazione del sensore per garantire il 100% di umidit\u00e0.[\/et_pb_text][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;30px|30px|30px|30px|false|false&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;rgba(0,0,0,0.23)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"boxColumn\">\n<div class=\"boxContent\">\n<h3><strong>Nota:  <\/strong><\/h3>\n<p><span>Tutti gli ISE a giunzione liquida hanno una durata di circa sei mesi. Qualsiasi puntale sostituibile ISE pi\u00f9 vecchio di sei mesi dovrebbe essere sostituito. <\/span><\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-ion-selective-electrodes.webp&#8221; alt=&#8221;elettrodi selettivi per ioni solinst eureka ise&#8221; title_text=&#8221;Elettrodi selettivi ionici Solinst Eureka ISE&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_height=&#8221;500px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Elettrodi selettivi agli ioni ISE per sonde di qualit\u00e0 dell&#8217;acqua<br \/><\/strong><\/h2>\n<p><strong>Gamma \/ Unit\u00e0<\/strong><\/p>\n<ul>\n<li>Ammonio<span class=\"Apple-tab-span\"> <\/span>da 0 a 100mg\/I come azoto<\/li>\n<li>Nitrato<span class=\"Apple-tab-span\"> <\/span>da 0 a 100 mg\/I come azoto<\/li>\n<li>Cloruro<span class=\"Apple-tab-span\"> <\/span>da 0,5 a 18.000 mg\/I<\/li>\n<li>Sodio<span class=\"Apple-tab-span\"> <\/span>da 0,05 a 20.000 mg\/I<\/li>\n<li>Calcio<span class=\"Apple-tab-span\"> <\/span>da 0 a 40.000 mg\/I<\/li>\n<li>Bromuro<span class=\"Apple-tab-span\"> <\/span>da 0 a 80.000 mg\/I<\/li>\n<\/ul>\n<div>\n<p><strong>Precisione<\/strong><\/p>\n<ul>\n<li>\u00b110% della lettura o 2 mg\/L w.i.g.<\/li>\n<\/ul>\n<p><strong>Risoluzione<\/strong><\/p>\n<ul>\n<li>0.1<\/li>\n<\/ul>\n<p><strong>Calibrazione<\/strong><\/p>\n<ul>\n<li>due punti<\/li>\n<\/ul>\n<p><strong>Manutenzione<\/strong><\/p>\n<ul>\n<li>pulizia, sostituzione periodica delle punte del sensore<\/li>\n<\/ul>\n<p><strong>Durata del sensore<\/strong><\/p>\n<ul>\n<li>sei mesi<\/li>\n<\/ul>\n<p><strong>Tipo di sensore<\/strong><\/p>\n<ul>\n<li>membrana liquida o solida<\/li>\n<\/ul>\n<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1ODA3In19@&#8221; button_text=&#8221;Richiedi un preventivo&#8221; admin_label=&#8221;get quote button&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;c9e00792-1360-4998-8cf9-5f6772c944ba&#8221; global_module=&#8221;46404&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Come si posizionano le misure ISE di Solinst Eureka rispetto agli altri?<\/strong><\/h2>\n<p>Poich\u00e9 tutti i produttori utilizzano meccanismi di base simili, non ci sono grandi differenze tra i sensori ISE presenti sul mercato. Tuttavia, l&#8217;elettrodo di riferimento a giunzione fluida di Solinst Eureka offre una migliore stabilit\u00e0 a lungo termine rispetto all&#8217;elettrodo di riferimento a elettrolita gelificato. <\/p>\n<p>La differenza tra attivit\u00e0 e concentrazione nella calibrazione degli elettrodi iono-selettivi 24 marzo 2010 L&#8217;elettrodo di riferimento pu\u00f2 essere facilmente rigenerato svitando la punta, riempiendo il sensore con elettrolita fresco e riavvitando la punta.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Spiegazione semplificata<br \/>\n<\/strong><strong>Elettrodi selettivi ionici ISE<\/strong><\/h2>\n<p>Pi\u00f9 ioni cercano di muoversi in una soluzione acquosa, pi\u00f9 si ostacolano a vicenda e quindi diminuisce l'&#8221;attivit\u00e0&#8221; ionica. Un elettrodo ionoselettivo (ISE) misura l&#8217;attivit\u00e0 di uno ione, che \u00e8 sempre inferiore alla sua reale concentrazione. Il numero riportato sul flacone di una soluzione di calibrazione ISE \u00e8 l&#8217;attivit\u00e0 dello ione specificato. Quando calibri un ISE, devi digitare quel numero di attivit\u00e0 perch\u00e9 Manta sa che l&#8217;ISE non \u00e8 abbastanza intelligente da fornire un numero di concentrazione. Quindi il Manta, molto pi\u00f9 intelligente, utilizza la lettura della conducibilit\u00e0 della soluzione per stimare di quanto deve aumentare la lettura dell&#8217;attivit\u00e0 dell&#8217;ISE per produrre una lettura della concentrazione. Ecco perch\u00e9 la lettura subito dopo la calibrazione \u00e8 pi\u00f9 alta del numero di calibrazione appena digitato.[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;3676f7e6-7b83-4698-94ce-2cc9fa9ae43d&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Concentrazione ionica<\/strong><\/h2>\n<p>Se si mescolano 0,05 milligrammi (mg) di sale da cucina (cloruro di sodio, NaCl) in 1 litro di acqua pura, \u00e8 chiaro che si ha una concentrazione di 0,05 mg\/litro di NaCl. Ma qual \u00e8 la concentrazione di cloruro? Sappiamo che il sodio e il cloro hanno un peso molecolare di 11 e 17 rispettivamente. Quindi:   <\/p>\n<ul>\n<li>17 \/ (11 + 17) = 61%, il che significa che lo ione cloruro costituisce il 61% del peso di NaCl.<\/li>\n<li>61% (0,05 mg\/l) = 0,03 mg\/l, il che significa che la concentrazione di ioni cloruro nella tua soluzione \u00e8 di 0,03 mg\/l (e possiamo assumere che lo ione sodio costituisca 0,02 mg\/l, nel caso qualcuno se lo chieda)<\/li>\n<\/ul>\n<p>Per confermare la concentrazione di cloruro si possono utilizzare i metodi standard di chimica analitica.<\/p>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;f0ff9324-d775-4951-8fd2-7c0df1fe47a5&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1ODA3In19@&#8221; button_text=&#8221;Richiedi un preventivo&#8221; admin_label=&#8221;get quote button&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;c9e00792-1360-4998-8cf9-5f6772c944ba&#8221; global_module=&#8221;46404&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;3676f7e6-7b83-4698-94ce-2cc9fa9ae43d&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][dvmd_table_maker tbl_top_left_mode=&#8221;on&#8221; tbl_responsive_break_by=&#8221;row&#8221; tbl_chead_cell_color=&#8221;rgba(10,10,10,0.59)&#8221; tbl_chead_text_wrap=&#8221;normal&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; tbl_chead_text_text_color=&#8221;#FFFFFF&#8221; tbl_chead_text_font_size=&#8221;18px&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#ed8b00&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;5px&#8221; button_letter_spacing=&#8221;0px&#8221; button_font=&#8221;|600||on|||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][dvmd_table_maker_item col_content=&#8221;Sensor<br \/>\nIon Selective Electrodes (ISE&#8217;s)<br \/>\nIon Selective Electrodes (ISE&#8217;s)<br \/>\nIon Selective Electrodes (ISE&#8217;s)<br \/>\nIon Selective Electrodes (ISE&#8217;s)<br \/>\nIon Selective Electrodes (ISE&#8217;s)<br \/>\nIon Selective Electrodes (ISE&#8217;s)&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/dvmd_table_maker_item][dvmd_table_maker_item col_content=&#8221;Parameter<br \/>\nammonium<br \/>\nnitrate<br \/>\nchloride<br \/>\nsodium<br \/>\ncalcium<br \/>\nbromide&#8221; col_column_max_width=&#8221;1fr&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/dvmd_table_maker_item][dvmd_table_maker_item col_content=&#8221;Range<br \/>\n0 to 100 mg\/l as nitrogen<br \/>\n0 to 100 mg\/l as nitrogen<br \/>\n0.5 to 18,000 mg\/l<br \/>\n0.05 to 20,000 mg\/l<br \/>\n0 to 40,000 mg\/l<br \/>\n0 to 80,000 mg\/l&#8221; col_column_max_width=&#8221;1fr&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/dvmd_table_maker_item][dvmd_table_maker_item col_content=&#8221;Resolution<br \/>\n0.01<br \/>\n0.1<br \/>\n0.1<br \/>\n0.1<br \/>\n0.1<br \/>\n0.1&#8243; col_column_max_width=&#8221;1fr&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/dvmd_table_maker_item][dvmd_table_maker_item col_content=&#8221;Accuracy<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.<br \/>\n\u00b110% of reading or 2mg\/L w.i.g.&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/dvmd_table_maker_item][dvmd_table_maker_item col_content=&#8221;Comments<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement<br \/>\ncorrected for ionic strength (via conductivity readings); the accuracy specification relies on non-trivial maintenance practice and frequent calibration near the temperature of measurement; sensors require periodic tip replacement&#8221; col_column_max_width=&#8221;3fr&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; col_tcell_text_font=&#8221;||||||||&#8221; col_tcell_text_font_size=&#8221;16px&#8221; col_chead_text_font=&#8221;|700|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/dvmd_table_maker_item][\/dvmd_table_maker][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;f0ff9324-d775-4951-8fd2-7c0df1fe47a5&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjQ1ODA3In19@&#8221; button_text=&#8221;Richiedi un preventivo&#8221; admin_label=&#8221;get quote button&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;c9e00792-1360-4998-8cf9-5f6772c944ba&#8221; global_module=&#8221;46404&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||9px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner saved_specialty_column_type=&#8221;3_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Prodotti correlati<\/strong><\/h2>\n<p>[\/et_pb_text][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0px||1em||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#d3d3d3&#8243; global_module=&#8221;69009&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/solinst-eureka-multi-parameter-probes.webp&#8221; alt=&#8221;sonde per acqua multiparametro solinst eureka&#8221; title_text=&#8221;Sonde d&#039;acqua multiparametro Solinst Eureka&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MDM3In19@&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; border_color_all=&#8221;#bcbcbc&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/instruments\/solinst-eureka\/water-quality-sondes\/manta-plumultiparameter-probes\/\" title=\"Sonde di qualit\u00e0 dell'acqua serie Manta\">Sonde di qualit\u00e0 dell&#8217;acqua serie Manta<\/a><\/h3>\n<p><a href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/\" title=\"Sonde di qualit\u00e0 dell'acqua Solinst Eureka\"><strong>Solinst Eureka<\/strong><\/a><span>  offre la pi\u00f9 ampia selezione di tecnologie per sensori di qualit\u00e0 dell&#8217;acqua del settore. Oltre alle configurazioni standard, ogni sonda pu\u00f2 essere personalizzata per la vostra applicazione specifica. Scegliete i sensori che preferite per riempire completamente le sonde pi\u00f9 grandi, oppure aggiungete un pacco batteria per convertire la sonda in un dispositivo di registrazione. <\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MDM3In19@&#8221; button_text=&#8221;Sonde per la qualit\u00e0 dell&apos;acqua Manta&#8221; button_alignment=&#8221;left&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#ff8500&#8243; button_border_radius=&#8221;20px&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#d3d3d3&#8243; global_module=&#8221;69010&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-trimeter-water-quality-sonde-965&#215;500-1.webp&#8221; alt=&#8221;sonde di qualit\u00e0 dell&#039;acqua solinst eureka trimeter&#8221; title_text=&#8221;Sonde per la qualit\u00e0 dell&#039;acqua Solinst Eureka Trimeter&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY0OTQwIn19@&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; border_color_all=&#8221;#bcbcbc&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; link_option_url=&#8221;https:\/\/www.solinst.com\/products\/level-measurement-devices\/103-tag-line\/&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sonde-per-la-qualita-dellacqua\/trimeter\/\" title=\"Sonda di qualit\u00e0 dell'acqua Manta Trimeter\">Sonda di qualit\u00e0 dell&#8217;acqua Manta Trimeter<\/a><\/h3>\n<p><span>Il <a href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sonde-per-la-qualita-dellacqua\/trimeter\/\" title=\"Sonda Trimeter a basso costo per la qualit\u00e0 dell'acqua\"><strong>Trimetro<\/strong><\/a> contiene un sensore* qualsiasi dall&#8217;elenco dei parametri del sensore, oltre ai sensori di temperatura e profondit\u00e0 (entrambi opzionali). Ad esempio, una configurazione Trimeter potrebbe essere costituita da torbidit\u00e0, temperatura e profondit\u00e0.  Un altro esempio potrebbe essere quello del DO e della temperatura.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY0OTQwIn19@&#8221; button_text=&#8221;Sonda di qualit\u00e0 dell&apos;acqua Manta Trimeter&#8221; button_alignment=&#8221;left&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#ff8500&#8243; button_border_radius=&#8221;20px&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#d3d3d3&#8243; global_module=&#8221;69121&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/03\/5001-easyprobe-water-quality-sondes.webp&#8221; alt=&#8221;sonde per la qualit\u00e0 dell&#039;acqua solinst eureka easyprobe&#8221; title_text=&#8221;Sonde per la qualit\u00e0 dell&#039;acqua Solinst Eureka EasyProbe&#8221; url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MTQ3In19@&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;url&#8221; _module_preset=&#8221;default&#8221; border_color_all=&#8221;#bcbcbc&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><a href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sonde-per-la-qualita-dellacqua\/sonda-per-la-qualita-dellacqua-easyprobe\/\" title=\"EasyProbe: Sonde per la qualit\u00e0 dell'acqua\">EasyProbe: Sonde per la qualit\u00e0 dell&#8217;acqua<\/a><\/h3>\n<p><span>La <a href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sonde-per-la-qualita-dellacqua\/sonda-per-la-qualita-dellacqua-easyprobe\/\" title=\"Sonda per la qualit\u00e0 dell'acqua EasyProbe\"><strong>EasyProbe<\/strong><\/a>di Solinst Eureka, \u00e8 un monitor della qualit\u00e0 dell&#8217;acqua ad alte prestazioni ed economico. \u00c8 ideale per il controllo a campione, la telemetria a distanza, la didattica, la ricerca, l&#8217;acquacoltura e altro ancora. Il modello EasyProbe20 comprende sensori di temperatura, ossigeno disciolto, conducibilit\u00e0 e pH, mentre il modello EasyProbe30 aggiunge un sensore di torbidit\u00e0.   Le sonde multiple Eureka sono note per la loro affidabilit\u00e0, con una garanzia di tre anni su tutti i sensori, e hanno i costi di manutenzione pi\u00f9 bassi del settore.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjY1MTQ3In19@&#8221; button_text=&#8221;Sonde per la qualit\u00e0 dell&apos;acqua Manta Easy Probe&#8221; button_alignment=&#8221;left&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#ff8500&#8243; button_border_radius=&#8221;20px&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#d3d3d3&#8243; global_module=&#8221;44627&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/3001-levelogger-5-ltc.webp&#8221; alt=&#8221;solinstogger 5 ltc livello dell&#039;acqua temperatura dell&#039;acqua e conduttivit\u00e0 dell&#039;acqua datalogger&#8221; title_text=&#8221;Solinstogger 5 Ltc Livello dell&#039;acqua Temperatura dell&#039;acqua e conduttivit\u00e0 dell&#039;acqua Datalogger&#8221; url=&#8221;https:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; border_color_all=&#8221;#bcbcbc&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Registrazione dei dati di livello, temperatura e conducibilit\u00e0 dell&#8217;acqua<\/h3>\n<p>Il <a href=\"https:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/\" title=\"Levelogger 5 LTC Registratore di dati di temperatura e conducibilit\u00e0 di livello\"><strong>Levelogger 5 LTC<\/strong><\/a> misura e registra le fluttuazioni del livello dell&#8217;acqua, la temperatura e la conducibilit\u00e0. \u00c8 programmato per registrare a intervalli di 2 secondi. Include una batteria di 8 anni, una memoria per 100.000 serie di letture e 6 intervalli di pressione. Un rivestimento privo di PFAS (all&#8217;interno e all&#8217;esterno) garantisce una resistenza superiore alla corrosione e all&#8217;abrasione.   <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.solinst.com\/products\/dataloggers-and-telemetry\/3001-levelogger-series\/ltc-levelogger\/&#8221; button_text=&#8221;Versatile registratore di dati di conduttivit\u00e0&#8221; button_alignment=&#8221;left&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#ff8500&#8243; button_border_radius=&#8221;20px&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][et_pb_row_inner column_structure=&#8221;1_2,1_2&#8243; make_equal=&#8221;on&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-items: center;&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#d3d3d3&#8243; global_module=&#8221;44750&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/01\/107-tlc-meter.webp&#8221; alt=&#8221;solinst modello 107 tlc meter per la profilazione della temperatura e della conducibilit\u00e0&#8221; title_text=&#8221;Misuratore Tlc Solinst modello 107 per la profilazione della temperatura e della conducibilit\u00e0&#8221; url=&#8221;https:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/&#8221; align=&#8221;center&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;100%&#8221; border_color_all=&#8221;#bcbcbc&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column_inner][et_pb_column_inner type=&#8221;1_2&#8243; _builder_version=&#8221;4.25.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; header_2_line_height=&#8221;1.3em&#8221; custom_margin_tablet=&#8221;0px||||false|false&#8221; custom_margin_phone=&#8221;0px||||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Misuratore TLC &#8211; Misura con precisione temperatura, livello e conduttivit\u00e0<\/h3>\n<p>A <a href=\"https:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/\" title=\"Profilazione della temperatura e della conducibilit\u00e0 dell'acqua con il misuratore TLC\"><strong>Misuratore TLC<\/strong><\/a> fornisce misurazioni accurate e stabili della temperatura e della conducibilit\u00e0, visualizzate su un comodo display LCD per una facile lettura. Il livello statico dell&#8217;acqua e la profondit\u00e0 delle letture vengono letti su un nastro piatto Solinst, marcato con precisione al laser ogni mm o 1\/100 ft. La lunghezza del nastro \u00e8 disponibile fino a 300 m (1000 ft).  <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/www.solinst.com\/products\/level-measurement-devices\/107-tlc-meter\/&#8221; button_text=&#8221;Profilazione della temperatura e della conduttivit\u00e0&#8221; button_alignment=&#8221;left&#8221; button_alignment_tablet=&#8221;center&#8221; button_alignment_phone=&#8221;center&#8221; button_alignment_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;18px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#FFFFFF&#8221; button_border_color=&#8221;#ff8500&#8243; button_border_radius=&#8221;20px&#8221; button_icon=&#8221;&#x3d;||divi||400&#8243; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Adobe Analytics Code&#8221; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||4px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_code admin_label=&#8221;Codice AA per questa pagina&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<!-- SiteCatalyst code version: H.21. Copyright 1996-2010 Adobe, Inc. All Rights Reserved More info available at http:\/\/www.omniture.com --><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\" src=\"\/\/www.solinst.com\/s_code.js\"><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->s.pageName=\"5001 ise ion selective electrodes\"<!-- [et_pb_line_break_holder] -->s.server=\"\"<!-- [et_pb_line_break_holder] -->s.channel=\"products\"<!-- [et_pb_line_break_holder] -->s.pageType=\"\"<!-- [et_pb_line_break_holder] -->s.prop1=\"solinst eureka\"<!-- [et_pb_line_break_holder] -->s.prop2=\"5001 water quality sensors\"<!-- [et_pb_line_break_holder] -->s.prop3=\"5001 ise ion selective electrodes\"<!-- [et_pb_line_break_holder] -->s.prop4=\"\"<!-- [et_pb_line_break_holder] -->s.prop5=\"\"<!-- [et_pb_line_break_holder] -->s.prop6=\"\"<!-- [et_pb_line_break_holder] -->s.prop7=\"\"<!-- [et_pb_line_break_holder] -->s.prop8=\"\"<!-- [et_pb_line_break_holder] -->s.prop9=\"\"<!-- [et_pb_line_break_holder] -->s.prop10=\"\"<!-- [et_pb_line_break_holder] -->s.prop11=\"\"<!-- [et_pb_line_break_holder] -->s.prop12=\"\"<!-- [et_pb_line_break_holder] -->s.prop13=\"\"<!-- [et_pb_line_break_holder] -->s.prop14=\"\"<!-- [et_pb_line_break_holder] -->s.prop15=\"\"<!-- [et_pb_line_break_holder] -->s.prop16=\"\"<!-- [et_pb_line_break_holder] -->s.prop17=\"\"<!-- [et_pb_line_break_holder] -->s.prop18=\"\"<!-- [et_pb_line_break_holder] -->s.prop19=\"\"<!-- [et_pb_line_break_holder] -->s.prop20=\"\"<!-- [et_pb_line_break_holder] -->s.prop21=\"\"<!-- [et_pb_line_break_holder] -->s.prop22=\"\"<!-- [et_pb_line_break_holder] -->s.prop23=\"\"<!-- [et_pb_line_break_holder] -->s.prop24=\"\"<!-- [et_pb_line_break_holder] -->s.prop25=\"\"<!-- [et_pb_line_break_holder] -->s.prop26=\"\"<!-- [et_pb_line_break_holder] -->s.prop27=\"\"<!-- [et_pb_line_break_holder] -->s.prop28=\"\"<!-- [et_pb_line_break_holder] -->s.prop29=\"\"<!-- [et_pb_line_break_holder] -->s.prop30=\"\"<!-- [et_pb_line_break_holder] -->s.prop31=\"\"<!-- [et_pb_line_break_holder] -->s.prop32=\"\"<!-- [et_pb_line_break_holder] -->s.prop33=\"\"<!-- [et_pb_line_break_holder] -->s.hier1=\"solinst:products:solinst eureka:5001 water quality sensors:5001 ise ion selective electrodes\"<!-- [et_pb_line_break_holder] --><!-- [et_pb_line_break_holder] -->\/* Conversion Variables *\/<!-- [et_pb_line_break_holder] -->s.campaign=\"\"<!-- [et_pb_line_break_holder] -->s.events=\"\"<!-- [et_pb_line_break_holder] -->s.eVar1=\"\"<!-- [et_pb_line_break_holder] -->s.eVar2=\"\"<!-- [et_pb_line_break_holder] -->s.eVar3=\"\"<!-- [et_pb_line_break_holder] -->s.eVar4=\"\"<!-- [et_pb_line_break_holder] -->s.eVar5=\"\"<!-- [et_pb_line_break_holder] -->s.eVar6=\"\"<!-- [et_pb_line_break_holder] -->s.eVar7=\"\"<!-- [et_pb_line_break_holder] -->s.eVar8=\"\"<!-- [et_pb_line_break_holder] -->s.eVar9=\"\"<!-- [et_pb_line_break_holder] -->s.eVar10=\"\"<!-- [et_pb_line_break_holder] -->s.eVar11=\"\"<!-- [et_pb_line_break_holder] -->s.eVar12=\"\"<!-- [et_pb_line_break_holder] -->s.eVar13=\"\"<!-- [et_pb_line_break_holder] -->s.eVar14=\"\"<!-- [et_pb_line_break_holder] -->s.eVar15=\"\"<!-- [et_pb_line_break_holder] -->s.eVar16=\"\"<!-- [et_pb_line_break_holder] -->s.eVar17=\"\"<!-- [et_pb_line_break_holder] -->s.state=\"\"<!-- [et_pb_line_break_holder] -->s.zip=\"\"<!-- [et_pb_line_break_holder] -->\/************* DO NOT ALTER ANYTHING BELOW THIS LINE ! **************\/<!-- [et_pb_line_break_holder] -->var s_code=s.t();if(s_code)document.write(s_code)\/\/--><\/script><!-- [et_pb_line_break_holder] --><script language=\"JavaScript\" type=\"text\/javascript\"><!--<!-- [et_pb_line_break_holder] -->if(navigator.appVersion.indexOf('MSIE')>=0)document.write(unescape('%3C')+'!-'+'-')<!-- [et_pb_line_break_holder] -->\/\/--><\/script><noscript><a href=\"https:\/\/www.omniture.com\" title=\"Analisi web\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/solinst.d2.sc.omtrdc.net\/b\/ss\/solinst-prod\/1\/H.21--NS\/0\" height=\"1\" width=\"1\" border=\"0\" alt=\"\"><\/a><\/noscript><!--\/DO NOT REMOVE\/--><!-- [et_pb_line_break_holder] --><!-- End SiteCatalyst code version: H.21. -->[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elettrodi selettivi ionici ISE<div class=\"et_pb_module dsm_breadcrumbs dsm_breadcrumbs_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module_inner\">\n\t\t\t\t\t<nav class=\"dsm_breadcrumbs_wrap\">\n\t\t\t\t<ul class=\"dsm_breadcrumbs\" itemscope itemtype=\"https:\/\/schema.org\/BreadcrumbList\">\t\t\t<li class=\"dsm_breadcrumbs_item dsm_home_item dsm_home_item_custom\" itemprop=\"itemListElement\" itemscope\n\t\t\titemtype=\"https:\/\/schema.org\/ListItem\">\n\t\t\t\t<a href=\"https:\/\/www.solinst.com\/it\/\" itemprop=\"item\" target=\"\">\n\t\t\t\t\t<span class='dsm_home_text_wrapper'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"et-pb-icon dsm_home_icon\">\ue009<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"dsm_home_text\" itemprop=\"name\">\n\t\t\t\t\t\t\t\tHome\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t<meta itemprop=\"position\" content=\"1\" \/>\n\t\t\t<\/li>\n\n\t\t<li class=\"dsm_breadcrumbs_separator\"> <span class=\"et-pb-icon dsm_separator_icon\">5<\/span><\/li><\/ul>\n\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t<\/div> Solinst Eureka2113 Wells Branch Pkwy, Suite 4400Austin, TX, USA78728 Tel: +1 512-302-4333Fax: +1 512-251-6842email: eureka@solinst.com &nbsp; Dati accurati sul livello dell&#8217;acqua Strumenti affidabili che durano nel tempo&nbsp; &nbsp; &nbsp; &nbsp; &nbsp;Perch\u00e9 dovrei voler misurare ioni specifici? Gli elettrodi iono-selettivi (ISE) sono una classe di sensori che rispondono alla presenza di ioni specifici, come il sodio (Na+) o il bromuro (Br). Vengono utilizzati insieme a un elettrodo di riferimento e riportano le concentrazioni degli ioni in mg\/L. Gli ISE pi\u00f9 comuni misurano l&#8217;ammonio (NH4+), il nitrato (NO3-) o il cloruro (Cl-). L&#8217;ammonio e il nitrato sono importanti perch\u00e9 sono indicatori di nutrienti a base di azoto. Vengono spesso utilizzati per rilevare la contaminazione da parte di impianti di trattamento delle acque reflue o attivit\u00e0 agricole. Le misurazioni del cloruro sono spesso utilizzate come indicatori di contaminazione da parte dell&#8217;acqua di mare o di altre fonti di contaminazione che contengono livelli di cloruro superiori a quelli previsti nelle acque naturali. Sono disponibili circa 30 altri ISE; alcuni funzionano meglio di altri. I cambiamenti nelle tendenze a lungo termine degli ioni specifici possono segnalare la necessit\u00e0 di uno studio chimico pi\u00f9 dettagliato dell&#8217;acqua e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":139147,"parent":64090,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"folder":[288],"class_list":["post-67795","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell&#039;acqua<\/title>\n<meta name=\"description\" content=\"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell&#039;acqua. Una classe di sensori che risponde alla presenza di ioni specifici come il sodio o il bromuro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elettrodi selettivi ionici Solinst Eureka ISE\" \/>\n<meta property=\"og:description\" content=\"Scoprite le capacit\u00e0 degli elettrodi selettivi ionici e come misurano ioni specifici nei vostri progetti di qualit\u00e0 dell&#039;acqua.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/\" \/>\n<meta property=\"og:site_name\" content=\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T21:26:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/featureimages-eureka-ion-selective-electrodes.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Elettrodi selettivi ionici Solinst Eureka ISE\" \/>\n<meta name=\"twitter:description\" content=\"Scoprite le capacit\u00e0 degli elettrodi selettivi ionici e come misurano ioni specifici nei vostri progetti di qualit\u00e0 dell&#039;acqua.\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/\",\"name\":\"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featureimages-eureka-ion-selective-electrodes.webp\",\"datePublished\":\"2025-03-07T14:40:46+00:00\",\"dateModified\":\"2026-05-13T21:26:43+00:00\",\"description\":\"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua. Una classe di sensori che risponde alla presenza di ioni specifici come il sodio o il bromuro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featureimages-eureka-ion-selective-electrodes.webp\",\"contentUrl\":\"https:\\\/\\\/www.solinst.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/featureimages-eureka-ion-selective-electrodes.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/sensori-di-qualita-dellacqua\\\/elettrodi-selettivi-ionici-ise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solinst Eureka\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/prodotti\\\/solinst-eureka\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Sensori di qualit\u00e0 dell&#8217;acqua\",\"item\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/instruments\\\/solinst-eureka\\\/water-quality-sensors\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Elettrodi selettivi ionici ISE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/\",\"name\":\"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers\",\"description\":\"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.solinst.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua","description":"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua. Una classe di sensori che risponde alla presenza di ioni specifici come il sodio o il bromuro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/","og_locale":"it_IT","og_type":"article","og_title":"Elettrodi selettivi ionici Solinst Eureka ISE","og_description":"Scoprite le capacit\u00e0 degli elettrodi selettivi ionici e come misurano ioni specifici nei vostri progetti di qualit\u00e0 dell'acqua.","og_url":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/","og_site_name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","article_modified_time":"2026-05-13T21:26:43+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/featureimages-eureka-ion-selective-electrodes.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"Elettrodi selettivi ionici Solinst Eureka ISE","twitter_description":"Scoprite le capacit\u00e0 degli elettrodi selettivi ionici e come misurano ioni specifici nei vostri progetti di qualit\u00e0 dell'acqua.","twitter_misc":{"Tempo di lettura stimato":"27 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/","url":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/","name":"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua","isPartOf":{"@id":"https:\/\/www.solinst.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/#primaryimage"},"image":{"@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/#primaryimage"},"thumbnailUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/featureimages-eureka-ion-selective-electrodes.webp","datePublished":"2025-03-07T14:40:46+00:00","dateModified":"2026-05-13T21:26:43+00:00","description":"Elettrodi selettivi ionici ISE: Monitoraggio della qualit\u00e0 dell'acqua. Una classe di sensori che risponde alla presenza di ioni specifici come il sodio o il bromuro.","breadcrumb":{"@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/#primaryimage","url":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/featureimages-eureka-ion-selective-electrodes.webp","contentUrl":"https:\/\/www.solinst.com\/wp-content\/uploads\/2025\/11\/featureimages-eureka-ion-selective-electrodes.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/sensori-di-qualita-dellacqua\/elettrodi-selettivi-ionici-ise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.solinst.com\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.solinst.com\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Solinst Eureka","item":"https:\/\/www.solinst.com\/it\/prodotti\/solinst-eureka\/"},{"@type":"ListItem","position":4,"name":"Sensori di qualit\u00e0 dell&#8217;acqua","item":"https:\/\/www.solinst.com\/it\/instruments\/solinst-eureka\/water-quality-sensors\/"},{"@type":"ListItem","position":5,"name":"Elettrodi selettivi ionici ISE"}]},{"@type":"WebSite","@id":"https:\/\/www.solinst.com\/it\/#website","url":"https:\/\/www.solinst.com\/it\/","name":"Solinst Groundwater and Surface Water Monitoring Instrumentation, Water Level Meters, Interface Meters, Dataloggers","description":"High quality groundwater monitoring instruments and surface water monitoring instruments including water level meters, interface meters, groundwater samplers, dataloggers and more!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.solinst.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/pages\/67795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/comments?post=67795"}],"version-history":[{"count":0,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/pages\/67795\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/pages\/64090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/media\/139147"}],"wp:attachment":[{"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/media?parent=67795"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.solinst.com\/it\/wp-json\/wp\/v2\/folder?post=67795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}